{"id":133151,"date":"2025-09-02T22:53:48","date_gmt":"2025-09-02T20:53:48","guid":{"rendered":"https:\/\/exaudi.org\/?p=133151"},"modified":"2025-09-02T23:33:56","modified_gmt":"2025-09-02T21:33:56","slug":"maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/","title":{"rendered":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano"},"content":{"rendered":"<p>La Pontificia Academia Mariana Internacional ha invitado a Ricardo Grzona, presidente de la Fundaci\u00f3n Ram\u00f3n Pan\u00e9, a exponer en el XVI Congreso Mariol\u00f3gico y Mariano que se celebrar\u00e1 en Roma. Su ponencia, titulada \u201cMar\u00eda en la fe de los j\u00f3venes, el ejemplo de Ram\u00f3n Pan\u00e9\u201d, busca rescatar una memoria hist\u00f3rica que enlaza el nacimiento de la Evangelizaci\u00f3n en Am\u00e9rica con la fuerza misionera de la juventud, siempre bajo el amparo de la Virgen Mar\u00eda.<\/p>\n<p><iframe title=\"Spotify Embed: Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/7BEmbtkttc3R08NCChVT48?utm_source=oembed\"><\/iframe><\/p>\n<h3><strong>Un viaje a 1494: la primera Eucarist\u00eda en el Continente Americano<\/strong><\/h3>\n<p>En su intervenci\u00f3n, Grzona llevar\u00e1 a los asistentes a un momento fundacional: 1494, a\u00f1o en que se celebr\u00f3 la primera Eucarist\u00eda en el Nuevo Mundo. Aquella misa tuvo un elemento profundamente simb\u00f3lico: en el altar se encontraba una imagen de la Virgen de Montserrat, regalo de la Reina Isabel la Cat\u00f3lica para los territorios reci\u00e9n evangelizados.<\/p>\n<p>Entre los presentes estaba el joven Ram\u00f3n Pan\u00e9, un fraile jer\u00f3nimo que, enviado por Crist\u00f3bal Col\u00f3n, se convertir\u00eda en el primer evangelizador de Am\u00e9rica y en un pionero del anuncio del Evangelio a los pueblos originarios.<\/p>\n<p>\u201cEste dato hist\u00f3rico nos recuerda que la Virgen Mar\u00eda ha estado presente desde el primer instante en que la Iglesia celebr\u00f3 la fe en Am\u00e9rica\u201d, explica Grzona. \u201cY no solo estuvo presente, sino que ha acompa\u00f1ado cada paso del camino misionero, inspirando a los j\u00f3venes a ser testigos valientes de Cristo\u201d.<\/p>\n<h3><strong>J\u00f3venes evangelizadores a lo largo de la historia<\/strong><\/h3>\n<p>La conferencia de Grzona estar\u00e1 estructurada en cinco momentos hist\u00f3ricos que abarcan 531 a\u00f1os de Evangelizaci\u00f3n, mostrando c\u00f3mo las nuevas generaciones han sido portadoras y renovadoras de la fe. Desde los j\u00f3venes misioneros de los primeros siglos hasta los l\u00edderes juveniles actuales, el estudio revela una constante: la misi\u00f3n florece cuando la juventud y Mar\u00eda caminan juntas.<br \/>\nGrzona subrayar\u00e1 que, en cada \u00e9poca, la figura de Mar\u00eda ha servido de modelo, inspiraci\u00f3n y gu\u00eda. Desde los tiempos de Pan\u00e9 hasta los desaf\u00edos actuales de la evangelizaci\u00f3n digital, la Madre de Jes\u00fas ha sido el \u201crostro materno\u201d que impulsa a los j\u00f3venes a anunciar el Evangelio con audacia y alegr\u00eda.<\/p>\n<h3><strong>Un evento que re\u00fane a expertos de todo el mundo<\/strong><\/h3>\n<p>El XVI Congreso Mariol\u00f3gico y Mariano es una cita de alto nivel que convoca a te\u00f3logos, historiadores, pastores y especialistas marianos de los cinco continentes. Este a\u00f1o, el encuentro tendr\u00e1 un \u00e9nfasis particular en el papel de Mar\u00eda en la historia y misi\u00f3n de la Iglesia, con especial atenci\u00f3n a la cultura juvenil y los desaf\u00edos contempor\u00e1neos.<br \/>\nLas actas oficiales del Congreso recoger\u00e1n \u00edntegramente la ponencia de Grzona, dejando constancia de esta investigaci\u00f3n y ofreciendo una herramienta de formaci\u00f3n para catequistas, pastoral juvenil y estudios marianos en todo el mundo.<\/p>\n<h3><strong>Mar\u00eda y los j\u00f3venes: una alianza que no se interrumpe<\/strong><\/h3>\n<p>La propuesta de Grzona no se limita a una mirada al pasado, sino que plantea un desaf\u00edo presente: reactivar el protagonismo evangelizador de los j\u00f3venes, enraizado en la historia y guiado por la Virgen Mar\u00eda.<\/p>\n<p>\u201cSi desde 1494 la Virgen ha estado al lado de los j\u00f3venes evangelizadores, no podemos dejar de invitarla a ser parte del camino de esta generaci\u00f3n. Su presencia es garant\u00eda de que la misi\u00f3n permanece viva y fecunda\u201d, concluye Grzona.<\/p>\n<p>\ud83d\udccc Datos clave del Congreso<\/p>\n<ul>\n<li><strong>Evento<\/strong>: XVI Congreso Mariol\u00f3gico y Mariano<\/li>\n<li><strong>Organiza<\/strong>: Pontificia Academia Mariana Internacional<\/li>\n<li><strong>Lugar<\/strong>: Ciudad del Vaticano, Roma 3-6 Septiembre 2025<\/li>\n<li><strong>Tema de la ponencia<\/strong>: \u201cMar\u00eda en la fe de los j\u00f3venes, el ejemplo de Ram\u00f3n Pan\u00e9\u201d<\/li>\n<li><strong>Ponente<\/strong>: Ricardo Grzona, presidente de la Fundaci\u00f3n Ram\u00f3n Pan\u00e9<\/li>\n<li><strong>Eje hist\u00f3rico<\/strong>: Desde la primera Eucarist\u00eda en Am\u00e9rica (1494) hasta la actualidad, con cinco momentos hist\u00f3ricos clave.<\/li>\n<\/ul>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-133158 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/Copia-de-Copia-de-Julio-Tudela.jpg?resize=940%2C788&#038;ssl=1\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/Copia-de-Copia-de-Julio-Tudela.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/Copia-de-Copia-de-Julio-Tudela.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/Copia-de-Copia-de-Julio-Tudela.jpg?resize=770%2C645&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/Copia-de-Copia-de-Julio-Tudela.jpg?resize=500%2C419&amp;ssl=1 500w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Fundaci\u00f3n Ram\u00f3n Pan\u00e9 presentar\u00e1 c\u00f3mo Mar\u00eda y la juventud han sido protagonistas en la Evangelizaci\u00f3n de Am\u00e9rica desde 1494 hasta hoy<\/p>\n","protected":false},"author":15,"featured_media":133154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[132],"tags":[71088,71087,71097,17412,43915,2091,71098,71096,71091,71095,71090,45167,12959,71099,21737,71089,71093,71092,1401,58880,71094],"class_list":["post-133151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vaticano-es","tag-congreso-mariano-vaticano","tag-congreso-mariologico-2025","tag-congreso-roma-2025","tag-evangelizacion-digital","tag-evangelizacion-en-america-latina","tag-fundacion-ramon-pane","tag-historia-de-la-evangelizacion","tag-iglesia-catolica-vaticano","tag-jovenes-y-maria","tag-juventud-evangelizadora","tag-maria-evangelizacion-america","tag-maria-madre-de-la-iglesia","tag-mariologia","tag-mision-juvenil-catolica","tag-pastoral-juvenil","tag-pontificia-academia-mariana-internacional","tag-primera-eucaristia-en-america","tag-ramon-pane-evangelizador","tag-ricardo-grzona","tag-trending-es-151","tag-virgen-de-montserrat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"El presidente de la Fundaci\u00f3n Ram\u00f3n Pan\u00e9 presentar\u00e1 c\u00f3mo Mar\u00eda y la juventud han sido protagonistas en la Evangelizaci\u00f3n de Am\u00e9rica desde 1494 hasta hoy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-02T20:53:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T21:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano\",\"datePublished\":\"2025-09-02T20:53:48+00:00\",\"dateModified\":\"2025-09-02T21:33:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/\"},\"wordCount\":689,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/17339499847909.png?fit=660%2C440&ssl=1\",\"keywords\":[\"congreso mariano vaticano\",\"congreso mariol\u00f3gico 2025\",\"congreso roma 2025\",\"evangelizaci\u00f3n digital\",\"evangelizaci\u00f3n en Am\u00e9rica Latina\",\"Fundaci\u00f3n Ram\u00f3n Pan\u00e9\",\"historia de la evangelizaci\u00f3n\",\"iglesia cat\u00f3lica vaticano\",\"j\u00f3venes y mar\u00eda\",\"juventud evangelizadora\",\"mar\u00eda evangelizaci\u00f3n am\u00e9rica\",\"Mar\u00eda Madre de la Iglesia\",\"Mariolog\u00eda\",\"misi\u00f3n juvenil cat\u00f3lica\",\"Pastoral Juvenil\",\"pontificia academia mariana internacional\",\"primera eucarist\u00eda en am\u00e9rica\",\"ram\u00f3n pan\u00e9 evangelizador\",\"Ricardo Grzona\",\"Trending\",\"virgen de montserrat\"],\"articleSection\":[\"Vaticano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/\",\"name\":\"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/17339499847909.png?fit=660%2C440&ssl=1\",\"datePublished\":\"2025-09-02T20:53:48+00:00\",\"dateModified\":\"2025-09-02T21:33:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/17339499847909.png?fit=660%2C440&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/17339499847909.png?fit=660%2C440&ssl=1\",\"width\":660,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/","og_locale":"es_ES","og_type":"article","og_title":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi","og_description":"El presidente de la Fundaci\u00f3n Ram\u00f3n Pan\u00e9 presentar\u00e1 c\u00f3mo Mar\u00eda y la juventud han sido protagonistas en la Evangelizaci\u00f3n de Am\u00e9rica desde 1494 hasta hoy","og_url":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2025-09-02T20:53:48+00:00","article_modified_time":"2025-09-02T21:33:56+00:00","og_image":[{"width":660,"height":440,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png","type":"image\/png"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano","datePublished":"2025-09-02T20:53:48+00:00","dateModified":"2025-09-02T21:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/"},"wordCount":689,"image":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png?fit=660%2C440&ssl=1","keywords":["congreso mariano vaticano","congreso mariol\u00f3gico 2025","congreso roma 2025","evangelizaci\u00f3n digital","evangelizaci\u00f3n en Am\u00e9rica Latina","Fundaci\u00f3n Ram\u00f3n Pan\u00e9","historia de la evangelizaci\u00f3n","iglesia cat\u00f3lica vaticano","j\u00f3venes y mar\u00eda","juventud evangelizadora","mar\u00eda evangelizaci\u00f3n am\u00e9rica","Mar\u00eda Madre de la Iglesia","Mariolog\u00eda","misi\u00f3n juvenil cat\u00f3lica","Pastoral Juvenil","pontificia academia mariana internacional","primera eucarist\u00eda en am\u00e9rica","ram\u00f3n pan\u00e9 evangelizador","Ricardo Grzona","Trending","virgen de montserrat"],"articleSection":["Vaticano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/","url":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/","name":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png?fit=660%2C440&ssl=1","datePublished":"2025-09-02T20:53:48+00:00","dateModified":"2025-09-02T21:33:56+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png?fit=660%2C440&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png?fit=660%2C440&ssl=1","width":660,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/maria-y-los-jovenes-la-voz-de-america-que-resonara-en-el-vaticano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda y los j\u00f3venes: la voz de Am\u00e9rica que resonar\u00e1 en el Vaticano"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/09\/17339499847909.png?fit=660%2C440&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-yDB","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/133151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=133151"}],"version-history":[{"count":6,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/133151\/revisions"}],"predecessor-version":[{"id":133163,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/133151\/revisions\/133163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/133154"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=133151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=133151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=133151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}