{"id":131600,"date":"2025-08-14T08:45:28","date_gmt":"2025-08-14T06:45:28","guid":{"rendered":"https:\/\/exaudi.org\/?p=131600"},"modified":"2025-08-25T10:18:31","modified_gmt":"2025-08-25T08:18:31","slug":"por-que-deberia-importarnos-la-etica","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/","title":{"rendered":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica?"},"content":{"rendered":"<p>Hablar de \u00e9tica hoy d\u00eda puede parecer que nos referimos a moralina, a serm\u00f3n dominical, a normas r\u00edgidas que proh\u00edben lo que nos gusta hacer\u2026. sin embargo, nada m\u00e1s lejos de la realidad. Este art\u00edculo pretende contribuir a valorar el papel que la \u00e9tica, a\u00fan de manera inconsciente, juega en nuestras vidas y como contribuye a que seamos lo m\u00e1s felices posibles<\/p>\n<p>Actualmente asistimos a lo que se podr\u00eda llamar una cierta descomposici\u00f3n de la \u00e9tica, o al menos a una falta de aplicaci\u00f3n, se habla incluso de una crisis de valores. Por una parte, se podr\u00eda decir que hay un obscurecimiento en la conciencia moral de muchos grupos humanos, pero, sobre todo, una falta de integraci\u00f3n \u00e9tica en la vida.<\/p>\n<p>Sobre la naturaleza humana, podemos afirmar que achacamos el origen de muchos problemas actuales a la falta de \u00e9tica en la vida.<\/p>\n<p>Para ello, y sin \u00e1nimo de aburrirles con disertaciones filos\u00f3ficas, hay que se\u00f1alar que la \u00e9tica, es una ciencia, no depende de la religi\u00f3n, sus principios y postulados son v\u00e1lidos para todos en todas las \u00e9pocas, al tomar decisiones nos comportamos de manera \u00e9tica y nos sugiere el camino hacia la paz interior.<\/p>\n<p>Veamos cada uno de estos temas brevemente:<\/p>\n<h3><strong>Es una ciencia<\/strong><\/h3>\n<p>La palabra \u00e9tica se emplea para significar el estudio filos\u00f3fico de la moral (G\u00f3mez P\u00e9rez 1993). Es parte de la filosof\u00eda, que es una ciencia, y por tanto est\u00e1 apoyada en argumentos. Por ejemplo: no se limita a decir \u00a8no se debe mentir\u00a8, sino que argumenta que es malo mentir, porque la mentira es contraria a la veracidad, y la veracidad es necesaria para la convivencia social, lo cual es un bien humano fundamental.<\/p>\n<p>Pero al no ser una ciencia exacta, como pueden serlo las matem\u00e1ticas o la f\u00edsica, sus postulados son f\u00e1cilmente cuestionables.<\/p>\n<p>A nadie en su sano juicio se le ocurrir\u00eda opinar que no est\u00e1 de acuerdo con la ley de la gravedad, sin embargo, las conclusiones de las leyes \u00e9ticas como: no es correcto matar, robar, etc\u2026 son objeto de debates con diferentes argumentos a favor y en contra. Es cierto que existe una \u00e9tica general que trata sobre el estudio de los principios del comportamiento y una \u00e9tica aplicada que nos indica, seg\u00fan las circunstancias, la concreci\u00f3n pr\u00e1ctica de esos principios generales, esto \u00faltimo, es lo que algunos fil\u00f3sofos llaman moral.<\/p>\n<h3><strong>Es independiente de la religi\u00f3n<\/strong><\/h3>\n<p>Por ser una ciencia, sus conclusiones son v\u00e1lidas para todas las personas, independientemente de su credo religioso, es decir, no s\u00f3lo para los cristianos. El conocimiento de la \u00e9tica sirve para orientar adecuadamente la propia vida. La \u00e9tica estudia el comportamiento del hombre tal como debe ser para que est\u00e9 de acuerdo con su naturaleza humana. El hombre es el mismo en Per\u00fa y en cualquier otra parte del mundo, todo aquello que da\u00f1a su naturaleza, que le hace da\u00f1o como persona, ocurre en cualquier parte del mundo.<\/p>\n<p>Hemos de reconocer, sin embargo, que, aunque la \u00e9tica tiene un estatus cient\u00edfico independiente de la religi\u00f3n, muchas de las leyes \u00e9ticas coinciden con principios y normas religiosas, por ejemplo, los Diez Mandamientos, o la moral budista.<\/p>\n<h3><strong>Sus principios son v\u00e1lidos para todo el mundo<\/strong><\/h3>\n<p>La \u00e9tica no es solamente patrimonio de Occidente, aparece en todas las grandes culturas, porque los problemas humanos a los que responde son universales y su soluci\u00f3n tambi\u00e9n est\u00e1 basada en una inspiraci\u00f3n global. Los grandes principios rectores de la conducta humana son compartidos por toda la humanidad y son formulados en cualquier \u00e1mbito social, aunque, como rama de la filosof\u00eda, la \u00e9tica es un invento griego, Arist\u00f3teles es el primer sistematizador de la \u00e9tica, sus leyes, son v\u00e1lidas para todas las personas, independientemente de su lugar, \u00e9poca de nacimiento y de sus creencias religiosas.<\/p>\n<h3><strong>Todos somos \u00e9ticos cuando tomamos decisiones<\/strong><\/h3>\n<p>Si nos detenemos a analizar lo que hacemos cada uno de nosotros en nuestro d\u00eda a d\u00eda, nos daremos cuenta, de que pasamos el d\u00eda tomando decisiones: desde que me levanto (qu\u00e9 ropa me pongo, qu\u00e9 tomo de desayuno, c\u00f3mo empiezo el d\u00eda, que ruta sigo\u2026) hasta el final del d\u00eda. Y aunque muchas de esas decisiones podemos decir que las tomamos de manera autom\u00e1tica, no por ello dejan de ser libres y voluntarias.<\/p>\n<p>Esto es importante, porque al ser libres tenemos que asumir las consecuencias que se derivan de ellas, es decir, ser responsables de nuestros actos; y por otro lado, no podemos obviar que, cuando actuamos (y previamente a la acci\u00f3n hay una decisi\u00f3n), vamos adquiriendo una serie de h\u00e1bitos que con el tiempo, nos ir\u00e1n convirtiendo en mejores o peores personas.<\/p>\n<p>Muchas veces nos encontramos en la vida con situaciones que nos parecen malas, pero nos damos cuenta de que, si esas acciones no dependen de nosotros, no las llamaremos buenas en sentido moral, sino que las llamamos buenas o malas seg\u00fan fortuna: buena suerte o mala suerte.<\/p>\n<p>Como se\u00f1alaba Leonardo Polo, estricta y propiamente, decimos bueno y malo de lo que hacemos seg\u00fan decisiones libres. No podemos decir, \u201cQue bueno me ha tocado la loter\u00eda\u201d, porque es algo que escapa a nuestra decisi\u00f3n, no decidimos que nos toque la loter\u00eda, ocurre, sucede, con gran fortuna, claro, pero utilizar la palabra bueno para algo que escapa a nuestra capacidad de acci\u00f3n no es \u00e9ticamente correcto. Bueno y malo, cobran significado en tanto que elegimos, con libertad, de ah\u00ed su car\u00e1cter \u00e9tico, y por lo tanto, despu\u00e9s debemos asumir la responsabilidad por la consecuencia de nuestras acciones o decisiones (Sell\u00e9s 1999).<\/p>\n<p>Esto est\u00e1 en estrecha relaci\u00f3n con la existencia de una norma: haz el bien y no hagas el mal.<\/p>\n<p>Lo bueno, lo moral es lo debido, y lo malo es lo no debido, pero no en cuanto me acontece, sino en tanto que lo decido, que tengo la posibilidad de cumplirlo y hacerlo, o de no cumplirlo y no hacerlo.<\/p>\n<p>Seg\u00fan propone Leonardo Polo, la \u00e9tica no es un adorno, un a\u00f1adido del hombre, sino que forma, y eso, es la entra\u00f1a misma de su actuar. Todo lo que el hombre hace tiene que ver con la \u00e9tica (Polo 1996). \u00a0No podemos olvidar que cuando actuamos lo hacemos buscando lograr algo, conseguir un objetivo. Los fil\u00f3sofos cl\u00e1sicos llaman a esto bien, bienes. En su \u00c9tica a Nic\u00f3maco, Arist\u00f3teles se\u00f1ala que el bien es aquello a lo que todas las cosas tienden (Sell\u00e9s 1999). Entonces Polo sostiene que hay dos tipos de fines: aquellos que son por s\u00ed mismos, que se buscan y se aman por s\u00ed mismos, en primer lugar; y los bienes \u00fatiles, o intermedios, que llevan a los bienes anteriores. Los bienes \u00fatiles, se buscan con vistas a otras cosas, para lograr otras cosas. El dinero es un ejemplo de bien \u00fatil o intermedio, ya que usualmente las personas no quieren el dinero por s\u00ed mismo, sino por lo que pueden comprar con el dinero.<\/p>\n<p>\u00bfCu\u00e1l es el bien que, en \u00faltima instancia, busca el hombre? Arist\u00f3teles, en su \u201c\u00c9tica a Nic\u00f3maco\u201d; se\u00f1ala que es la felicidad, porque la elegimos siempre por ella misma y nunca por otra cosa (Arist\u00f3teles 2004).<\/p>\n<h3><strong>Nos sugiere el camino de la paz interior para alcanzar la felicidad<\/strong><\/h3>\n<p>El comportamiento del hombre viene siempre regido por una finalidad, que es, lo que se propone alcanzar con sus acciones. El fin que persigue cuando act\u00faa, puede estar subordinado a otro y este a otro y as\u00ed sucesivamente, pero siempre, hay un fin m\u00e1s all\u00e1 del cual no se persigue otro, sino que se quiere en s\u00ed mismo. A este fin se le llama \u00a8fin \u00faltimo\u00a8. Podemos concluir, afirmando que se trata de la felicidad, y que la \u00e9tica nos ayuda a conducir nuestra vida de tal manera que alcancemos a ser felices (Ayll\u00f3n 2012).<\/p>\n<p>Para terminar, no olvidemos que el hombre es un ser inteligente, que, a diferencia de los animales, va configurando su propio destino, por lo tanto, toma decisiones libres, ya que est\u00e1 obligado a elegir (nuestro comportamiento no es instintivo) y la \u00e9tica es una gu\u00eda que, a trav\u00e9s de normas y leyes morales, nos ayuda a tomar decisiones correctas, con un impacto positivo en los dem\u00e1s, en la sociedad que nos rodea, que nos haga mejores personas, y por lo tanto, nos ayuda a encontrar la felicidad.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft size-full wp-image-132009\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Imagen1-1.jpg?resize=129%2C172&#038;ssl=1\" alt=\"\" width=\"129\" height=\"172\" \/><\/p>\n<p><em><strong>Ana Isabel Rap\u00fan Ruiz<\/strong><\/em><\/p>\n<h6><em>Profesora universitaria por 30 a\u00f1os ense\u00f1ando cursos de \u00e9tica. Actualmente coordina la l\u00ednea de \u00c9tica del departamento de Humanidades en la Universidad Peruana de Ciencias Aplicadas. Dedica su labor profesional a la ense\u00f1anza e investigaci\u00f3n de temas de \u00e9tica y Ciudadan\u00eda.<\/em><\/h6>\n<h6><em>Ha cursado el doctorado\u00a0 en Humanidades con menci\u00f3n en Cultura en la Universidad de Piura, y el doctorado en en Filosof\u00eda de la Acci\u00f3n y Direcci\u00f3n de organizaciones. IESE- Universidad de Navarra, Pamplona, Espa\u00f1a. Es Magister en Filosof\u00eda de la Acci\u00f3n Directiva por el IESE y la Universidad de Navarra, Espa\u00f1a y licenciada en Filosof\u00eda y Letras por la misma universidad.<\/em><\/h6>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-132014 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Rosa-Montenegro-1-1.jpg?resize=940%2C788&#038;ssl=1\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Rosa-Montenegro-1-1.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Rosa-Montenegro-1-1.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Rosa-Montenegro-1-1.jpg?resize=770%2C645&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/Rosa-Montenegro-1-1.jpg?resize=500%2C419&amp;ssl=1 500w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/p>\n<p>***<\/p>\n<p><strong>Bibliograf\u00eda.\u00a0 <\/strong><\/p>\n<h6>Arist\u00f3teles. (2004). <em>\u00c9tica a Nic\u00f3maco<\/em> (W. D. Ross, Trad.). Penguin Classics. (Trabajo original publicado en el siglo IV a.C.)<\/h6>\n<h6>Sell\u00e9s, J. F. (1999). Leonardo Polo, La voluntad y sus actos (II). Cuadernos de Anuario Filos\u00f3fico. Serie Universitaria, n\u00ba 60, Servicio de Publicaciones de la Universidad de Navarra, Pamplona, 1998, 68 p\u00e1gs.\u00a0<em>Studia Poliana<\/em>, (1), 122-12<\/h6>\n<h6>Polo, Leonardo (1996), \u00c9tica hacia una versi\u00f3n moderna de los temas cl\u00e1sicos. Madrid, AEDOS<\/h6>\n<h6>Ayll\u00f3n Jos\u00e9 Ram\u00f3n (2012) \u00c9tica Razonada. Madrid, Palabra.<\/h6>\n<h6>G\u00f3mez P\u00e9rez, Rafael (1993). Problemas morales de la existencia humana. Madrid, Magisterio Casals.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Ciencia universal que gu\u00eda nuestras decisiones y nos acerca a la felicidad<\/p>\n","protected":false},"author":168,"featured_media":131602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[69715,24044,69712,22883,43201,1793,65871,69721,69716,69713,69711,69719,51454,69718,69720,69717,23014,69710,69714,58880,23000],"class_list":["post-131600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-aristoteles-etica","tag-bien-y-mal","tag-ciencia-de-la-etica","tag-comportamiento-humano","tag-crisis-de-valores","tag-etica","tag-etica-aplicada","tag-etica-cotidiana","tag-etica-general","tag-etica-independiente-de-la-religion","tag-etica-y-felicidad","tag-felicidad-como-fin-ultimo","tag-filosofia-moral","tag-guia-etica","tag-habitos-y-etica","tag-moral-y-etica","tag-paz-interior","tag-principios-universales","tag-toma-de-decisiones-responsables","tag-trending-es-151","tag-valores-humanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Ciencia universal que gu\u00eda nuestras decisiones y nos acerca a la felicidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-14T06:45:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T08:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RHUM, revista de humanidades\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"RHUM, revista de humanidades\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/\"},\"author\":{\"name\":\"RHUM, revista de humanidades\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0e882721c581718638da53d8a4e65835\"},\"headline\":\"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica?\",\"datePublished\":\"2025-08-14T06:45:28+00:00\",\"dateModified\":\"2025-08-25T08:18:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/\"},\"wordCount\":1672,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1\",\"keywords\":[\"Arist\u00f3teles \u00e9tica\",\"bien y mal\",\"ciencia de la \u00e9tica\",\"comportamiento humano\",\"crisis de valores\",\"\u00c9tica\",\"\u00e9tica aplicada\",\"\u00e9tica cotidiana\",\"\u00e9tica general\",\"\u00e9tica independiente de la religi\u00f3n\",\"\u00e9tica y felicidad\",\"felicidad como fin \u00faltimo\",\"filosof\u00eda moral\",\"gu\u00eda \u00e9tica\",\"h\u00e1bitos y \u00e9tica\",\"moral y \u00e9tica\",\"paz interior\",\"principios universales\",\"toma de decisiones responsables\",\"Trending\",\"valores humanos\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/\",\"name\":\"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1\",\"datePublished\":\"2025-08-14T06:45:28+00:00\",\"dateModified\":\"2025-08-25T08:18:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0e882721c581718638da53d8a4e65835\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1\",\"width\":2560,\"height\":1701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/por-que-deberia-importarnos-la-etica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/0e882721c581718638da53d8a4e65835\",\"name\":\"RHUM, revista de humanidades\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g\",\"caption\":\"RHUM, revista de humanidades\"},\"description\":\"Revista RHUM es una publicaci\u00f3n que busca fusionar distintas dimensiones del pensamiento y la expresi\u00f3n cultural: Escritura creativa: fomenta la narrativa literaria y formas expresivas innovadoras. An\u00e1lisis filos\u00f3fico: incorpora reflexiones profundas sobre ideas, conceptos y paradigmas. Memoria hist\u00f3rica: apuesta por rescatar, revisitar y entender nuestro pasado, contribuyendo al recuerdo colectivo. Imaginaci\u00f3n est\u00e9tica: explora el arte y la sensibilidad como medios de interpretaci\u00f3n y reconexi\u00f3n con lo vivido. En resumen, RHUM se posiciona como un espacio interdisciplinar donde convergen la creatividad, la reflexi\u00f3n cr\u00edtica y el recuerdo hist\u00f3rico, con una mirada est\u00e9tica que enriquece cada contenido.\",\"sameAs\":[\"https:\\\/\\\/revistarhum.com\\\/\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/revista-rhum\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi","og_description":"Ciencia universal que gu\u00eda nuestras decisiones y nos acerca a la felicidad","og_url":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-08-14T06:45:28+00:00","article_modified_time":"2025-08-25T08:18:31+00:00","og_image":[{"width":2560,"height":1701,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg","type":"image\/jpeg"}],"author":"RHUM, revista de humanidades","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"RHUM, revista de humanidades","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/"},"author":{"name":"RHUM, revista de humanidades","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0e882721c581718638da53d8a4e65835"},"headline":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica?","datePublished":"2025-08-14T06:45:28+00:00","dateModified":"2025-08-25T08:18:31+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/"},"wordCount":1672,"image":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1","keywords":["Arist\u00f3teles \u00e9tica","bien y mal","ciencia de la \u00e9tica","comportamiento humano","crisis de valores","\u00c9tica","\u00e9tica aplicada","\u00e9tica cotidiana","\u00e9tica general","\u00e9tica independiente de la religi\u00f3n","\u00e9tica y felicidad","felicidad como fin \u00faltimo","filosof\u00eda moral","gu\u00eda \u00e9tica","h\u00e1bitos y \u00e9tica","moral y \u00e9tica","paz interior","principios universales","toma de decisiones responsables","Trending","valores humanos"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/","url":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/","name":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica? &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1","datePublished":"2025-08-14T06:45:28+00:00","dateModified":"2025-08-25T08:18:31+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/0e882721c581718638da53d8a4e65835"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1","width":2560,"height":1701},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/por-que-deberia-importarnos-la-etica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 deber\u00eda importarnos la \u00e9tica?"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/0e882721c581718638da53d8a4e65835","name":"RHUM, revista de humanidades","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73a31af62f1b6d1800d30c62e470f5a14e17074576331f7f1a8a72e21beae38?s=96&d=mm&r=g","caption":"RHUM, revista de humanidades"},"description":"Revista RHUM es una publicaci\u00f3n que busca fusionar distintas dimensiones del pensamiento y la expresi\u00f3n cultural: Escritura creativa: fomenta la narrativa literaria y formas expresivas innovadoras. An\u00e1lisis filos\u00f3fico: incorpora reflexiones profundas sobre ideas, conceptos y paradigmas. Memoria hist\u00f3rica: apuesta por rescatar, revisitar y entender nuestro pasado, contribuyendo al recuerdo colectivo. Imaginaci\u00f3n est\u00e9tica: explora el arte y la sensibilidad como medios de interpretaci\u00f3n y reconexi\u00f3n con lo vivido. En resumen, RHUM se posiciona como un espacio interdisciplinar donde convergen la creatividad, la reflexi\u00f3n cr\u00edtica y el recuerdo hist\u00f3rico, con una mirada est\u00e9tica que enriquece cada contenido.","sameAs":["https:\/\/revistarhum.com\/"],"url":"https:\/\/exaudi.org\/es\/author\/revista-rhum\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-yeA","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/08\/pexels-alexisricardoalaurin-2907605-scaled.jpg?fit=2560%2C1701&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/131600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=131600"}],"version-history":[{"count":4,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/131600\/revisions"}],"predecessor-version":[{"id":132017,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/131600\/revisions\/132017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/131602"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=131600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=131600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=131600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}