{"id":126856,"date":"2025-05-26T08:36:10","date_gmt":"2025-05-26T06:36:10","guid":{"rendered":"https:\/\/exaudi.org\/?p=126856"},"modified":"2025-05-26T12:37:47","modified_gmt":"2025-05-26T10:37:47","slug":"mirada-relacion-edistio-camere","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/","title":{"rendered":"La mirada crea \u00e1mbitos de relaci\u00f3n"},"content":{"rendered":"<p>La mirada crea \u00e1mbitos de relaci\u00f3n. Cuando se mira, nuestro \u201cyo\u201d se desplaza hasta lo mirado, fuera de su reducto se abre a novedosas formas de encuentro, se dispone a recibir, que es un modo de acoger a quien da. Al mirar realizamos un \u201cviaje\u201d desde lo m\u00e1s \u00edntimo de nuestro ser para \u201cponerlo\u201d en las pupilas, en la mirada. Por tanto, la mirada es vista y decodificada por lo que revela: el ser personal, el mundo interior. Si acoge, comprende, respeta y atiende, quien mira se muestra. Al mostrarse, la mirada se hace dial\u00f3gica. El di\u00e1logo es un ingrediente consustancial de la relaci\u00f3n humana. El hombre es apertura, capaz de abrirse a la realidad, en virtud de lo cual, su mirar no refleja, comunica su vivencia que, como suya es original. Pero al cruzarse con la mirada del \u201cotro\u201d intercambian originalidades con relaci\u00f3n a un mismo bien: la realidad.<\/p>\n<p><iframe title=\"Spotify Embed: La mirada crea \u00e1mbitos de relaci\u00f3n\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/1eYQNXYV4SEoY0LtOoTZLa?si=bb35524798b74ca9&#038;utm_source=oembed\"><\/iframe><\/p>\n<p>La mirada adem\u00e1s de revelar el propio interior es una apacible brisa que descubre y valora los dijes de un t\u00fa, \u201cno quieras despreciarme, que si color moreno en m\u00ed hallaste, ya bien puedes mirarme, despu\u00e9s que me miraste, que gracia y hermosura en m\u00ed dejaste.\u201d (San Juan de la Cruz). Con todo, hay miradas tiernas, fr\u00edas, crueles; miradas humildes, miradas soberbias, miradas limpias, miradas torvas, miradas penetrantes y miradas superficiales. Saber mirar a los ojos y leer lo que dicen las miradas es un arte que enjoya las relaciones interpersonales.<\/p>\n<p>Las miradas m\u00e1s hermosas son aquellas que proyectan lo m\u00e1s alto del ser humano: su inteligencia, su voluntad y su singularidad. Son las que trasmiten la comprensi\u00f3n y el amar con respecto a otras personas y al universo. Son aquellas miradas l\u00facidas y amorosas que dicen: \u00a1qu\u00e9 bueno que existas!\u201d \u201c\u00a1que alegr\u00eda verte y tenerte!\u201d. Es la mirada que se\u00f1orea tu ser as\u00ed y no de otro modo, \u201c<em>qu\u00edtate ya los trajes, las se\u00f1as, los retratos; yo no te quiero as\u00ed, disfrazada de otra, hija siempre de algo.\u00a0 Te quiero pura, libre, irreductible: t\u00fa.\u201d\u00a0<\/em> Es la mirada amorosa capaz de distinguir, entre una multitud, al amado. \u201c<em>S\u00e9 que cuando te llame entre todas las gentes del mundo, s\u00f3lo t\u00fa ser\u00e1s t\u00fa.\u201d<\/em> (Salinas) En suma, es la mirada de Dios, de una madre y de un coraz\u00f3n enamorado.<\/p>\n<p>Cuando la relaci\u00f3n se instrumentaliza, la mirada no confirma, cosifica y reduce. El contraataque es reafirmar la libertad anulando la suya que es un modo de reducirlo y pagarle con la misma moneda. El conflicto se hace presente en la relaci\u00f3n. \u00a0Ejemplos los hay de los m\u00e1s variados: pi\u00e9nsese en las relaciones conyugales en donde uno reduce a la esposa a quien lava, plancha, atiende a los hijos y se encarga de las micro decisiones; y, padre, es restado al que trae el dinero, arregla los grandes problemas y decide sobre las macro decisiones. De manera que, si alguno de ellos quiere opinar sobre algo \u201c<em>que no le compete<\/em>\u201d se le echa en cara su intromisi\u00f3n. En ambos casos, la persona es reemplazable. Puedo remplazar a un obrero por otro, a una esposa que lava, planche, cocine por una lavandera y cocinera profesional; y, a un esposo por uno que m\u00e1s provea y mejor administre.<\/p>\n<p>En el fondo, lo que hay es una hipertrofia del yo que no puede establecer ninguna relaci\u00f3n sin sentirse intimidado, y que la \u00fanica forma de superar la amenaza es reducir al t\u00fa en un reflejo del yo. \u00a0Los que no opinan como \u00e9l, est\u00e1n equivocados; los que opinan parecido a \u00e9l, est\u00e1n en lo cierto en lo que coinciden y equivocados en lo que discrepan; y los que opinan igual, no hacen otra cosa que repetirlo, son meros ep\u00edgonos sin gracia, ecos mortecinos de ideas de terceros.<\/p>\n<p>Finalmente, los ojos son la ventana del alma, dice la sabidur\u00eda popular; la f\u00edsica replica diciendo: \u201cs\u00f3lo si la ventana est\u00e1 limpia\u201d; a\u00fan la filosof\u00eda insiste: \u201cla luminosidad del alma desempa\u00f1a el vaho del cristal\u201d pero s\u00f3lo el amor distingue el <strong><em>brillo de los ojos.<\/em><\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-126883 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/voces-11.jpg?resize=940%2C788&#038;ssl=1\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/voces-11.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/voces-11.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/voces-11.jpg?resize=770%2C645&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/voces-11.jpg?resize=500%2C419&amp;ssl=1 500w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ventana al alma y puente de conexi\u00f3n humana<\/p>\n","protected":false},"author":108,"featured_media":126861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[26128,20069,25836,51115,599,10629,6010,9183,22139,60541,20060,60539,48554,10273,60540,4953,18841],"class_list":["post-126856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-autoexpresion","tag-comprension","tag-comunicacion-no-verbal","tag-conexion-humana","tag-dialogo","tag-edistio-camere","tag-emociones","tag-empatia","tag-interaccion-social","tag-intimidad","tag-mirada","tag-ojos","tag-percepcion","tag-relacion","tag-significado","tag-trending-es","tag-vinculos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Ventana al alma y puente de conexi\u00f3n humana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-26T06:36:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-26T10:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edistio C\u00e1mere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edistio C\u00e1mere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/\"},\"author\":{\"name\":\"Edistio C\u00e1mere\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/aa92f55756693d1030b8b20e6cc7a60e\"},\"headline\":\"La mirada crea \u00e1mbitos de relaci\u00f3n\",\"datePublished\":\"2025-05-26T06:36:10+00:00\",\"dateModified\":\"2025-05-26T10:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/\"},\"wordCount\":722,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1\",\"keywords\":[\"autoexpresi\u00f3n\",\"comprensi\u00f3n\",\"comunicaci\u00f3n no verbal\",\"conexi\u00f3n humana\",\"di\u00e1logo\",\"Edistio C\u00e1mere\",\"Emociones\",\"Empat\u00eda\",\"Interacci\u00f3n Social\",\"intimidad\",\"mirada\",\"ojos\",\"percepci\u00f3n\",\"RELACI\u00d3N\",\"significado\",\"Trending\",\"v\u00ednculos\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/\",\"name\":\"La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1\",\"datePublished\":\"2025-05-26T06:36:10+00:00\",\"dateModified\":\"2025-05-26T10:37:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/aa92f55756693d1030b8b20e6cc7a60e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1\",\"width\":2560,\"height\":1396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/mirada-relacion-edistio-camere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mirada crea \u00e1mbitos de relaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/aa92f55756693d1030b8b20e6cc7a60e\",\"name\":\"Edistio C\u00e1mere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g\",\"caption\":\"Edistio C\u00e1mere\"},\"description\":\"Especialista en Liderazgo y Direcci\u00f3n educativa\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/edistiocamere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/","og_locale":"es_ES","og_type":"article","og_title":"La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi","og_description":"Ventana al alma y puente de conexi\u00f3n humana","og_url":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-05-26T06:36:10+00:00","article_modified_time":"2025-05-26T10:37:47+00:00","og_image":[{"width":2560,"height":1396,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg","type":"image\/jpeg"}],"author":"Edistio C\u00e1mere","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Edistio C\u00e1mere","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/"},"author":{"name":"Edistio C\u00e1mere","@id":"https:\/\/exaudi.org\/#\/schema\/person\/aa92f55756693d1030b8b20e6cc7a60e"},"headline":"La mirada crea \u00e1mbitos de relaci\u00f3n","datePublished":"2025-05-26T06:36:10+00:00","dateModified":"2025-05-26T10:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/"},"wordCount":722,"image":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1","keywords":["autoexpresi\u00f3n","comprensi\u00f3n","comunicaci\u00f3n no verbal","conexi\u00f3n humana","di\u00e1logo","Edistio C\u00e1mere","Emociones","Empat\u00eda","Interacci\u00f3n Social","intimidad","mirada","ojos","percepci\u00f3n","RELACI\u00d3N","significado","Trending","v\u00ednculos"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/","url":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/","name":"La mirada crea \u00e1mbitos de relaci\u00f3n &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1","datePublished":"2025-05-26T06:36:10+00:00","dateModified":"2025-05-26T10:37:47+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/aa92f55756693d1030b8b20e6cc7a60e"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1","width":2560,"height":1396},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/mirada-relacion-edistio-camere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La mirada crea \u00e1mbitos de relaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/aa92f55756693d1030b8b20e6cc7a60e","name":"Edistio C\u00e1mere","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1775fbe340de944caeeb45f274a80a5a62f77fdffaafcadc491856f815f04f35?s=96&d=mm&r=g","caption":"Edistio C\u00e1mere"},"description":"Especialista en Liderazgo y Direcci\u00f3n educativa","url":"https:\/\/exaudi.org\/es\/author\/edistiocamere\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/05\/Gemini_Generated_Image_fkai55fkai55fkai-scaled.jpg?fit=2560%2C1396&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-x04","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/126856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=126856"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/126856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/126861"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=126856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=126856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=126856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}