{"id":12161,"date":"2026-04-19T07:30:20","date_gmt":"2026-04-19T05:30:20","guid":{"rendered":"https:\/\/exaudi.org\/?p=12161"},"modified":"2026-04-19T11:25:37","modified_gmt":"2026-04-19T09:25:37","slug":"beato-conrado-de-ascoli-19-abril","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/","title":{"rendered":"Beato Conrado de Ascoli, 19 de abril"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El beato Conrado de Ascoli naci\u00f3 el 18 de septiembre de 1234 en Ascoli Piceno, Italia. Formaba parte de una reconocida familia de ilustre abolengo: los Miliani. Uno de sus amigos de infancia era Jer\u00f3nimo Masci futuro general de la Orden franciscana y papa (Nicol\u00e1s IV), descendiente tambi\u00e9n de una relevante familia de la burgues\u00eda de Ascoli.<\/span><\/p>\n<p><iframe title=\"Spotify Embed: Beato Conrado de Ascoli, 19 de abril\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/2QKeRzJMXqHtpMKC1A4LVa?si=ed2914e1a4434f35&amp;utm_source=oembed\"><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\">Se cuenta que Conrado intu\u00eda el futuro que aguardaba a su compatriota porque siendo ni\u00f1os algunas veces se arrodillaba ante \u00e9l. Y como ese gesto fuera apreciado por otras personas que, como es natural, quisieron saber qu\u00e9 lo impulsaba, con toda naturalidad explic\u00f3 que ve\u00eda en \u00e9l al sucesor de Pedro. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Incluso vislumbraba en sus manos las llaves, s\u00edmbolo de la Iglesia, una apreciaci\u00f3n que solo pod\u00eda provenir de lo alto. Pues bien, esta feliz circunstancia que conllevaba su estrecha convivencia super\u00f3 lo anecd\u00f3tico ya que ambos compartieron su vocaci\u00f3n por la vida franciscana.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vistieron el h\u00e1bito de la Orden a la par en el convento de Ascoli, y siguieron una formaci\u00f3n paralela realizando su noviciado en As\u00eds. Pero la Providencia fue preparando a Jer\u00f3nimo para encarnar misiones de gobierno que marcaron el inicio de dos caminos divergentes entre estos hermanos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Ahora bien, unidos siempre por el ideal de Cristo, y en una misma vocaci\u00f3n, no dejaron de estar el uno en el coraz\u00f3n del otro. Y Jer\u00f3nimo acudir\u00eda al beato Conrado de Ascoli en otras circunstancias. Antes, desde 1255 a 1273, aqu\u00e9l pas\u00f3 por las Marcas y el Lacio, siendo lector de teolog\u00eda y predicador en Dalmacia-Croacia, a instancias de san Buenaventura que apreciaba su val\u00eda. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seguro que Conrado tuvo noticias tambi\u00e9n de su fruct\u00edfera intervenci\u00f3n diplom\u00e1tica en Constantinopla, labor que fue ensalzada porque la situaci\u00f3n creada entre la iglesia greco-bizantina y la cat\u00f3lica era altamente delicada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0Mientras la vida de Jer\u00f3nimo discurr\u00eda por esta senda, Conrado se hab\u00eda trasladado a Peruggia donde se doctor\u00f3, ense\u00f1\u00f3 teolog\u00eda y se dedic\u00f3 a evangelizar. Ambos fueron ejemplo de humildad y obediencia. Luego en el transcurso del cap\u00edtulo general de Lyon, el 19 de mayo de 1274 Jer\u00f3nimo fue designado ministro general de la Orden. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El \u00faltimo hab\u00eda sido san Buenaventura, pero el Ser\u00e1fico Doctor desde 1273 asum\u00eda la dignidad de cardenal. Muri\u00f3 el 17 de julio de ese a\u00f1o 1274. Una vez que Jer\u00f3nimo tom\u00f3 posesi\u00f3n de su nuevo oficio autoriz\u00f3 la partida de Conrado a tierras africanas, concretamente a Libia. Fue el primer misionero de Cirenaica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esa \u00e9poca Francia quer\u00eda invadir Espa\u00f1a y el papa Nicol\u00e1s III intervino para impedirlo a trav\u00e9s de Masci, asign\u00e1ndole como compa\u00f1ero de tan compleja misi\u00f3n al beato Conrado de Ascoli. Logrado este prop\u00f3sito, regresaron a Roma donde Masci fue nombrado cardenal en 1278. El beato pas\u00f3 dos a\u00f1os en Roma, y despu\u00e9s fue enviado a Par\u00eds donde imparti\u00f3 teolog\u00eda en su universidad. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero cuando Jer\u00f3nimo fue elegido pont\u00edfice en 1288 sucediendo a Honorio IV, lo reclam\u00f3 de nuevo. Tuvo en cuenta su autorizado juicio y estaba seguro de que ser\u00eda un excelente consejero. La vida de Conrado, celoso e incansable ap\u00f3stol de Cristo, hab\u00eda estado marcada por la humildad y la penitencia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se le ve\u00eda revestido de un \u00e1spero h\u00e1bito, caminaba con los pies descalzos, descansaba solamente unas pocas horas en una r\u00edgida tabla, ayunaba a pan y agua cuatro de los siete d\u00edas de la semana, y alentaba a todos a la conversi\u00f3n. Ten\u00eda una gran devoci\u00f3n por la Sant\u00edsima Trinidad y la Pasi\u00f3n de Cristo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fue un aspirante al martirio y siempre quiso unir sus sufrimientos a los del Redentor. Fue agraciado con el don de milagros y el de profec\u00eda. Entre la gente hab\u00eda cundido la idea, fraguada en lo que ve\u00edan, de que se hallaban ante un santo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nicol\u00e1s IV sab\u00eda que era un religioso de singular val\u00eda, y pens\u00f3 designarlo cardenal. Cuando este deseo lleg\u00f3 a o\u00eddos de Conrado, que se sent\u00eda llamado a encarnar el esp\u00edritu de anonadamiento, experiment\u00f3 un hondo sentimiento de desagrado. Pero se dispuso a obedecer. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es lo que hab\u00eda hecho Jer\u00f3nimo cuando fue elegido para desempe\u00f1ar las altas misiones que le encomendaron: asumir su contrariedad y abrazarse a la cruz. Llegado el momento de la despedida de los fieles, las palabras que pronunci\u00f3 el beato Conrado de Ascoli en la predicaci\u00f3n no eran m\u00e1s que el signo de lo que anidaba en su coraz\u00f3n. Glos\u00f3 maravillosamente las virtudes cristianas, ensalzando de forma especial el valor de la vida oculta en Cristo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esos momentos su salud estaba ya muy debilitada. Por eso, un viaje, que entonces era extenuante, le afect\u00f3 sobremanera. Y yendo camino de Roma no le qued\u00f3 m\u00e1s remedio que detenerse en Ascoli para gozo de todos, como \u00e9l mismo pudo comprobar a trav\u00e9s de las muestras de afecto que le dispensaron. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le quedaba \u00fanicamente un mes de vida. Hall\u00e1ndose en su ciudad natal, cay\u00f3 enfermo. Sab\u00eda que se encontraba a punto de entregar su alma a Dios porque le fue dado a conocer de antemano el d\u00eda y hora de su deceso. Pudo prepararse para ese momento tan anhelado, y el d\u00eda 19 de abril de 1289 ingres\u00f3 en el cielo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> La noticia produjo una especial consternaci\u00f3n porque ya era aclamado por su fama de virtud. Su hermano, compa\u00f1ero y amigo, pont\u00edfice Nicol\u00e1s IV, no ocult\u00f3 su dolor develando que, efectivamente, hab\u00eda pensado nombrar cardenal a este entra\u00f1able y fiel religioso. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s, profundamente conmovido mand\u00f3 erigir un mausoleo sobre la sepultura en San Lorenzo alle Piagge de Ascoli Piceno. El 28 de mayo de 1371 los restos de Conrado fueron depositados en la iglesia de San Francisco en la misma ciudad. P\u00edo VI determin\u00f3 concederle Oficio y Misa en su honor el 30 de agosto de 1783.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-162926 size-full alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=1080%2C1080&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=770%2C770&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2026\/04\/Copia-de-Santoral-3.jpg?resize=500%2C500&amp;ssl=1 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2208\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/02\/santoral-scaled-1.jpg?resize=262%2C370&#038;ssl=1\" alt=\"santoral Isabel Orellana\" width=\"262\" height=\"370\" \/><\/p>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6><em>\u00a9 <a href=\"https:\/\/exaudi.org\/es\/author\/isabelorellana\/\" target=\"_blank\" rel=\"noopener noreferrer\">Isabel Orellana Vilches<\/a>, 2018<\/em><br \/>\n<em>Autora vinculada a<\/em><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-41949\" src=\"https:\/\/i0.wp.com\/www.idente.org\/wp-content\/uploads\/logo-cedro-v01-843x295-1-e1603384654546.png?resize=80%2C28&#038;ssl=1\" alt=\"\" width=\"80\" height=\"28\" \/><br \/>\nObra protegida por derechos de autor.<br \/>\nInscrita en el Registro de la Propiedad Intelectual el 24 de noviembre de 2014.<br \/>\n________________<br \/>\nDerechos de edici\u00f3n reservados:<br \/>\nFundaci\u00f3n <a href=\"https:\/\/rielo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fernando Rielo<\/a><br \/>\nGoya 20, 4.\u00ba izq. int. 28001 Madrid<br \/>\nTlf.: (34) 91 575 40 91<br \/>\nCorreo electr\u00f3nico: fundacion@rielo.com<\/h6>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h6>Dep\u00f3sito legal: M-18664-2020<br \/>\nISBN: 978-84-946646-6-3<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Religioso franciscano<\/p>\n","protected":false},"author":23,"featured_media":12167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[74,2772],"tags":[1760,388,387,58880],"class_list":["post-12161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","category-santoral","tag-beato-conrado-de-ascoli","tag-isabel-orellana-vilches","tag-santoral","tag-trending-es-151"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-19T05:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T09:25:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Isabel Orellana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Orellana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/\"},\"author\":{\"name\":\"Isabel Orellana\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"headline\":\"Beato Conrado de Ascoli, 19 de abril\",\"datePublished\":\"2026-04-19T05:30:20+00:00\",\"dateModified\":\"2026-04-19T09:25:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/\"},\"wordCount\":1096,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Santoral-12.png?fit=2000%2C1200&ssl=1\",\"keywords\":[\"Beato Conrado de Ascoli\",\"Isabel Orellana Vilches\",\"Santoral\",\"Trending\"],\"articleSection\":[\"Iglesia y Mundo\",\"Santoral\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/\",\"name\":\"Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Santoral-12.png?fit=2000%2C1200&ssl=1\",\"datePublished\":\"2026-04-19T05:30:20+00:00\",\"dateModified\":\"2026-04-19T09:25:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\"},\"description\":\"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Santoral-12.png?fit=2000%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Santoral-12.png?fit=2000%2C1200&ssl=1\",\"width\":2000,\"height\":1200,\"caption\":\"Beato Conrado de Ascoli \u00a9 Vidassantas.blogspot.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/beato-conrado-de-ascoli-19-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beato Conrado de Ascoli, 19 de abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/64e18b96fd6118559a9217b5b3375fdc\",\"name\":\"Isabel Orellana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g\",\"caption\":\"Isabel Orellana\"},\"description\":\"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \\\"mirada\\\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/isabelorellana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a","description":"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/","og_locale":"es_ES","og_type":"article","og_title":"Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a","og_description":"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.","og_url":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2026-04-19T05:30:20+00:00","article_modified_time":"2026-04-19T09:25:37+00:00","og_image":[{"width":2000,"height":1200,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png","type":"image\/png"}],"author":"Isabel Orellana","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Isabel Orellana","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/"},"author":{"name":"Isabel Orellana","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"headline":"Beato Conrado de Ascoli, 19 de abril","datePublished":"2026-04-19T05:30:20+00:00","dateModified":"2026-04-19T09:25:37+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/"},"wordCount":1096,"image":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png?fit=2000%2C1200&ssl=1","keywords":["Beato Conrado de Ascoli","Isabel Orellana Vilches","Santoral","Trending"],"articleSection":["Iglesia y Mundo","Santoral"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/","url":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/","name":"Beato Conrado de Ascoli, 19 de abril - Exaudi Espa\u00f1a","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png?fit=2000%2C1200&ssl=1","datePublished":"2026-04-19T05:30:20+00:00","dateModified":"2026-04-19T09:25:37+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc"},"description":"Santoral del 19 de abril de 2021 sobre el beato Conrado de Ascoli, por Isabel Orellana Vilches y la Fundaci\u00f3n Fernando Rielo.","breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png?fit=2000%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png?fit=2000%2C1200&ssl=1","width":2000,"height":1200,"caption":"Beato Conrado de Ascoli \u00a9 Vidassantas.blogspot.com"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/beato-conrado-de-ascoli-19-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Beato Conrado de Ascoli, 19 de abril"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/64e18b96fd6118559a9217b5b3375fdc","name":"Isabel Orellana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51968380bbb6b22ae85c605634860366fd9a2a611c6341125115bca32cd6c171?s=96&d=mm&r=g","caption":"Isabel Orellana"},"description":"Isabel Orellana Vilches Misionera idente. Doctora en Filosof\u00eda por la Universidad Aut\u00f3noma de Barcelona con la tesis Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana. Ha cursado estudios de teolog\u00eda en la Universidad Pontificia de Salamanca. Con amplia actividad docente desde 1986, ha publicado libros como: Realismo y progreso cient\u00edfico en la epistemolog\u00eda popperiana, Universitat Aut\u00f2noma de Barcelona, 1993; El evangelio habla a los j\u00f3venes, Atenas, Madrid, 1997; Qu\u00e9 es... LA TOLERANCIA, Paulinas, Madrid, 1999; Pedagog\u00eda del dolor. Ensayo antropol\u00f3gico, Palabra, Madrid, 1999; En colaboraci\u00f3n con Enrique Rivera de Ventosa (\u2020) OFM. Cap. San Francisco de As\u00eds y Fernando Rielo: Convergencias. Respuestas desde la fe a los interrogantes del hombre de hoy, Universidad Pontificia, Salamanca, 2001; La \"mirada\" del cine. Recursos did\u00e1cticos del s\u00e9ptimo arte. Librer\u00eda Cervantes, Salamanca, 2001; Paradojas de la convivencia, San Pablo, Madrid, 2002; En la Universidad T\u00e9cnica Particular de Loja, Ecuador, ha publicado: La confianza. El arte de amar, 2002; Educar para la responsabilidad, 2003; Apuntes de \u00e9tica en Karl R. Popper, 2003; De soledades y comunicaci\u00f3n, 2005; Yo educo; t\u00fa respondes, 2008; Humanismo y fe en un crisol de culturas, 2008; Repensar lo cotidiano, 2008; Convivir: un constante desaf\u00edo, 2009; La l\u00f3gica del amor, 2010; El dolor del amor. Apuntes sobre la enfermedad y el dolor en relaci\u00f3n con la virtud heroica, el martirio y la vida santa. Seminario Diocesano de M\u00e1laga, 2006 y Universidad T\u00e9cnica Particular de Loja, Ecuador (2007). Cuenta con numerosas colaboraciones en obras colectivas, as\u00ed como relatos, cuentos, f\u00e1bula y novela juvenil, adem\u00e1s de art\u00edculos de tem\u00e1tica cient\u00edfica, pedag\u00f3gica y espiritual, que viene publicando en distintas revistas nacionales e internacionales. En 2012 culmin\u00f3 el santoral Llamados a ser santos y poco m\u00e1s tarde Epopeyas de amor prologado por mons. Fernando Sebasti\u00e1n. Es la bi\u00f3grafa oficial del fundador de su familia espiritual, autora de Fernando Rielo Pardal. Fundador de los Misioneros Identes, Descl\u00e9e de Brouwer, Bilbao, 2009. Culmina la biograf\u00eda completa. Encargada del santoral de ZENIT desde 2012 a 2020 y ahora en Exaudi","url":"https:\/\/exaudi.org\/es\/author\/isabelorellana\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2021\/04\/Santoral-12.png?fit=2000%2C1200&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-3a9","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/12161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=12161"}],"version-history":[{"count":4,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/12161\/revisions"}],"predecessor-version":[{"id":166894,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/12161\/revisions\/166894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/12167"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=12161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=12161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=12161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}