{"id":120554,"date":"2025-03-07T08:30:37","date_gmt":"2025-03-07T07:30:37","guid":{"rendered":"https:\/\/exaudi.org\/?p=120554"},"modified":"2025-03-06T10:07:21","modified_gmt":"2025-03-06T09:07:21","slug":"la-riqueza-del-corazon-y-la-palabra","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/","title":{"rendered":"La Riqueza del Coraz\u00f3n y la Palabra"},"content":{"rendered":"<p dir=\"auto\">El pasado domingo, escuchamos a Jes\u00fas hablar sobre la riqueza del coraz\u00f3n y c\u00f3mo esta se refleja en nuestras palabras. Esta ense\u00f1anza establece una relaci\u00f3n directa entre el coraz\u00f3n y el habla, destacando la importancia de la inteligencia ling\u00fc\u00edstica, que es la habilidad para utilizar el lenguaje de manera precisa y efectiva.<\/p>\n<p><iframe title=\"Spotify Embed: La Riqueza del Coraz\u00f3n y la Palabra\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/28pOdtRVom35Ewl0M1diYs?si=c056edf2fa9f410d&#038;utm_source=oembed\"><\/iframe><\/p>\n<p dir=\"auto\">La inteligencia ling\u00fc\u00edstica permite narrar experiencias \u00edntimas, reflexionar, comparar y resumir sucesos. Es fundamental para la persona, ya que est\u00e1 vinculada directamente al uso del lenguaje y a la raz\u00f3n. La dislexia, por ejemplo, dificulta el aprendizaje al afectar la capacidad de leer correctamente, lo que subraya la importancia de la palabra en nuestras vidas.<\/p>\n<p dir=\"auto\">La logoterapia, una rama de la psicolog\u00eda y la psiquiatr\u00eda, reconoce la profunda conexi\u00f3n entre la palabra y la persona. Esta relaci\u00f3n se extiende m\u00e1s all\u00e1 de la raz\u00f3n y la persona, abarcando tambi\u00e9n la vida espiritual. En el cristianismo, la palabra es central, ya que Jesucristo es considerado el Verbo, la palabra del Padre. La oraci\u00f3n cristiana se distingue por ser un di\u00e1logo entre dos libertades, un encuentro donde se da y se recibe la palabra.<\/p>\n<p dir=\"auto\">Sin embargo, vivimos en una \u00e9poca de crisis de la palabra. El relativismo dominante y la banalizaci\u00f3n de la palabra a trav\u00e9s de internet y las redes sociales han llevado a una comunicaci\u00f3n superficial y a la p\u00e9rdida de la profundidad en nuestras conversaciones. Esto afecta no solo nuestras relaciones personales y sociales, sino tambi\u00e9n nuestra relaci\u00f3n con Dios. La incapacidad de entender el lenguaje de la Biblia y de reflexionar sobre nuestras experiencias espirituales es una consecuencia directa de esta crisis.<\/p>\n<p dir=\"auto\">Para enfrentar esta situaci\u00f3n, es fundamental volver a darle a la palabra la dignidad que merece. Esto implica ayudar a otros a encontrar las palabras que reflejan lo que tienen en el coraz\u00f3n y a expresar sus experiencias de manera precisa. La escucha y el testimonio son dos ejercicios clave para lograrlo. Escuchar implica prestar atenci\u00f3n a la persona, no solo a su problema, y ayudarle a expresar lo que realmente siente. El testimonio, por otro lado, implica compartir nuestras propias experiencias de manera aut\u00e9ntica, volvi\u00e9ndonos vulnerables y permitiendo que el Esp\u00edritu Santo act\u00fae a trav\u00e9s de nosotros.<\/p>\n<p dir=\"auto\">En esta Cuaresma, estamos invitados a practicar la caridad de la palabra, ayudando a otros a encontrar las palabras que brotan de su coraz\u00f3n y compartiendo nuestras propias experiencias de manera aut\u00e9ntica. Esto no solo enriquecer\u00e1 nuestras relaciones personales y sociales, sino que tambi\u00e9n fortalecer\u00e1 nuestra conexi\u00f3n con Dios.<\/p>\n<p><iframe title=\"Palabra\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/TzlAeqBselA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-120558 alignnone\" src=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/voces-2.jpg?resize=940%2C788&#038;ssl=1\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/voces-2.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/voces-2.jpg?resize=300%2C251&amp;ssl=1 300w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/voces-2.jpg?resize=770%2C645&amp;ssl=1 770w, https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/voces-2.jpg?resize=500%2C419&amp;ssl=1 500w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Inteligencia Ling\u00fc\u00edstica y la Espiritualidad<\/p>\n","protected":false},"author":126,"featured_media":120555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[],"tags":[4610,2243,48185,5860,48187,26644,3975,448,1371,1019,3164,35311,48183,1020,445,48186,676,8711,48188,463,414,17250,8663,48184,2781,48189,15380],"class_list":["post-120554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-caridad","tag-comunicacion","tag-crisis-de-la-palabra","tag-cristianismo","tag-dislexia","tag-ensenanza-de-jesus","tag-escucha","tag-espiritu-santo","tag-espiritualidad","tag-evangelizacion","tag-fe-es","tag-inteligencia-emocional","tag-inteligencia-linguistica","tag-internet","tag-jesucristo","tag-logoterapia","tag-oracion","tag-palabra","tag-palabra-del-padre","tag-redes-sociales","tag-reflexion","tag-relaciones-personales","tag-relativismo","tag-riqueza-del-corazon","tag-testimonio","tag-verbo","tag-vida-espiritual"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"La Inteligencia Ling\u00fc\u00edstica y la Espiritualidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T07:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Herrera Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Herrera Campo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/\"},\"author\":{\"name\":\"Luis Herrera Campo\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\"},\"headline\":\"La Riqueza del Coraz\u00f3n y la Palabra\",\"datePublished\":\"2025-03-07T07:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/\"},\"wordCount\":479,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1\",\"keywords\":[\"caridad\",\"Comunicaci\u00f3n\",\"crisis de la palabra\",\"Cristianismo\",\"dislexia\",\"ense\u00f1anza de Jes\u00fas\",\"Escucha\",\"Esp\u00edritu Santo\",\"Espiritualidad\",\"Evangelizaci\u00f3n\",\"fe\",\"inteligencia emocional\",\"inteligencia ling\u00fc\u00edstica\",\"Internet\",\"Jesucristo\",\"logoterapia\",\"Oraci\u00f3n\",\"Palabra\",\"palabra del Padre\",\"Redes sociales\",\"Reflexi\u00f3n\",\"relaciones personales\",\"Relativismo\",\"riqueza del coraz\u00f3n\",\"Testimonio\",\"Verbo\",\"Vida espiritual\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/\",\"name\":\"La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1\",\"datePublished\":\"2025-03-07T07:30:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-riqueza-del-corazon-y-la-palabra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Riqueza del Coraz\u00f3n y la Palabra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\",\"name\":\"Luis Herrera Campo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"caption\":\"Luis Herrera Campo\"},\"description\":\"Nac\u00ed en Burgos, donde vivo. Soy sacerdote del Opus Dei.\",\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@luisherreracampo\\\/featured\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/luis-herrera-campo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/","og_locale":"es_ES","og_type":"article","og_title":"La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi","og_description":"La Inteligencia Ling\u00fc\u00edstica y la Espiritualidad","og_url":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-03-07T07:30:37+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg","type":"image\/jpeg"}],"author":"Luis Herrera Campo","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Luis Herrera Campo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/"},"author":{"name":"Luis Herrera Campo","@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc"},"headline":"La Riqueza del Coraz\u00f3n y la Palabra","datePublished":"2025-03-07T07:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/"},"wordCount":479,"image":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1","keywords":["caridad","Comunicaci\u00f3n","crisis de la palabra","Cristianismo","dislexia","ense\u00f1anza de Jes\u00fas","Escucha","Esp\u00edritu Santo","Espiritualidad","Evangelizaci\u00f3n","fe","inteligencia emocional","inteligencia ling\u00fc\u00edstica","Internet","Jesucristo","logoterapia","Oraci\u00f3n","Palabra","palabra del Padre","Redes sociales","Reflexi\u00f3n","relaciones personales","Relativismo","riqueza del coraz\u00f3n","Testimonio","Verbo","Vida espiritual"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/","url":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/","name":"La Riqueza del Coraz\u00f3n y la Palabra &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1","datePublished":"2025-03-07T07:30:37+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/la-riqueza-del-corazon-y-la-palabra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La Riqueza del Coraz\u00f3n y la Palabra"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc","name":"Luis Herrera Campo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","caption":"Luis Herrera Campo"},"description":"Nac\u00ed en Burgos, donde vivo. Soy sacerdote del Opus Dei.","sameAs":["https:\/\/www.youtube.com\/@luisherreracampo\/featured"],"url":"https:\/\/exaudi.org\/es\/author\/luis-herrera-campo\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-vmq","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/03\/pexels-jimbear-1309899-scaled.jpg?fit=2560%2C1706&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/120554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=120554"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/120554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/120555"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=120554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=120554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=120554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}