{"id":120063,"date":"2025-02-27T08:30:30","date_gmt":"2025-02-27T07:30:30","guid":{"rendered":"https:\/\/exaudi.org\/?p=120063"},"modified":"2025-02-26T18:26:13","modified_gmt":"2025-02-26T17:26:13","slug":"no-tengo-miedo-no-lo-tengais-vosotros","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/","title":{"rendered":"No tengo miedo. No lo teng\u00e1is vosotros"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\"><strong>Alex\u00e9i Navalni<\/strong>\u00a0naci\u00f3 el 4 de junio de 1976 cerca de Mosc\u00fa. Tras estudiar Derecho y m\u00e1s tarde Econom\u00eda, comenz\u00f3 su carrera pol\u00edtica con un enfoque nacionalista, una postura que posteriormente repudi\u00f3 tras su conversi\u00f3n al cristianismo. Su activismo evolucion\u00f3 hacia una lucha por la justicia y la libertad frente al sistema corrupto y autoritario de Vlad\u00edmir Putin.<\/p>\n<p><iframe title=\"Spotify Embed: No tengo miedo. No lo teng\u00e1is vosotros\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6nAB2ErmpqTul542lTJnz5?si=0335a2b8ef784977&#038;utm_source=oembed\"><\/iframe><\/p>\n<p>En 2020, su carrera pol\u00edtica sufri\u00f3 un giro dram\u00e1tico cuando fue envenenado, un atentado del que se recuper\u00f3 milagrosamente en Alemania. A pesar de conocer los riesgos, regres\u00f3 a Rusia, donde fue arrestado y sometido a una serie de juicios pol\u00edticos y traslados entre prisiones. Finalmente, termin\u00f3 en la colonia penal de m\u00e1xima seguridad de Harp, m\u00e1s all\u00e1 del C\u00edrculo Polar \u00c1rtico. El 16 de febrero de 2024, despu\u00e9s de 300 d\u00edas en aislamiento, falleci\u00f3 a los 47 a\u00f1os.<\/p>\n<p>Navalni\u00a0fue un disidente que desafi\u00f3 el autoritarismo de Putin y tambi\u00e9n el populismo y la corrupci\u00f3n en las democracias occidentales. Recientemente, se ha publicado un libro recopilatorio con sus reflexiones, entrevistas, intervenciones judiciales y escritos desde la c\u00e1rcel. Titulado <a href=\"https:\/\/edicionesencuentro.com\/libro\/no-tengo-miedo-no-lo-tengais-vosotros\/\" target=\"_blank\" rel=\"noopener\"><em>No tengo miedo, no lo teng\u00e1is vosotros<\/em><\/a>, el libro ha sido editado por Ediciones Encuentro.<\/p>\n<p>M\u00e1s all\u00e1 de su activismo, Navalni\u00a0fue un hombre profundamente comprometido con tres amores fundamentales: su familia, el bien com\u00fan y su fe. De ellos extrajo la fuerza para soportar con esperanza y humor el martirio pol\u00edtico que padeci\u00f3.<\/p>\n<h3><strong>Un amor por el bien com\u00fan<\/strong><\/h3>\n<p>Navalni\u00a0cre\u00eda en la lucha por ideas que merecen la pena tanto para vivir como para morir. Organiz\u00f3 numerosas manifestaciones en Mosc\u00fa, reuniendo a cientos de miles de personas. Sin embargo, insist\u00eda en que el verdadero cambio ocurr\u00eda en las almas de quienes participaban. Antes de una de estas manifestaciones, dijo:<\/p>\n<p style=\"text-align: center\"><em>\u00abLa gente pregunta con frecuencia: \u00bfQu\u00e9 puede cambiar esta manifestaci\u00f3n? Esta manifestaci\u00f3n nos cambiar\u00e1 a nosotros. Cambiar\u00e1 lo que dir\u00e9is a vuestros hijos y nietos cuando os pregunten sobre este periodo tremendo. Debemos salir a la calle por amor a nosotros mismos. Entonces Rusia dejar\u00e1 de ser un simple pa\u00eds y se distinguir\u00e1 del dictador demente responsable del fango que sigue deshonrando nuestra bandera, nuestra lengua y la misma palabra Rusia.\u00bb<\/em><\/p>\n<p>En sus juicios pol\u00edticos, Navalni\u00a0aprovechaba cada oportunidad para dirigirse a sus jueces con valent\u00eda. En una ocasi\u00f3n, se enfrent\u00f3 a ellos diciendo:<\/p>\n<p style=\"text-align: center\"><em>\u00abSi os fotografiara ahora a los tres, tambi\u00e9n a los representantes de la llamada parte afectada, todos bajar\u00e9is la mirada. Siempre fij\u00e1is la vista en la mesa cuando me dirijo a vosotros. No ten\u00e9is nada que decir. Todos me dec\u00eds la misma frase: &#8216;Alex\u00e9i Navalni, \u00bfentiende usted?&#8217;. Lo entiendo todo. Pero hay algo que no entiendo: \u00bfpor qu\u00e9 baj\u00e1is continuamente la mirada?\u00bb<\/em><\/p>\n<h3><strong>Un hombre de fe y esperanza<\/strong><\/h3>\n<p>En su 45\u00ba cumplea\u00f1os, desde la c\u00e1rcel, reflexion\u00f3 sobre su situaci\u00f3n con una mezcla de humor y determinaci\u00f3n:<\/p>\n<p style=\"text-align: center\"><em>\u00abPreferir\u00eda no tener que despertarme en esta perrera. Me gustar\u00eda desayunar con mi familia, recibir besos de mis hijos y abrir regalos. Pero la vida funciona de tal modo que el progreso social y un futuro mejor se logran solo si un determinado n\u00famero de personas est\u00e1n dispuestas a pagar un precio por su derecho a tener convicciones. Cuantas m\u00e1s personas haya, menos pagar\u00e1n todos, y llegar\u00e1 el d\u00eda en que decir la verdad y defender la justicia en Rusia ser\u00e1 algo normal y no algo peligroso.\u00bb<\/em><\/p>\n<p>Un a\u00f1o antes de su muerte, con motivo de su 46\u00ba cumplea\u00f1os, escribi\u00f3:<\/p>\n<p style=\"text-align: center\"><em>\u00abHoy cumplo 46 a\u00f1os y me encuentro fenomenal. Hay cosas que podr\u00edan mejorarse, claro, pero eso vale para todos. Estoy muy contento. Tengo una familia a la que quiero, compa\u00f1eros inteligentes que contin\u00faan nuestra obra com\u00fan. Y, sobre todo, tengo un inmenso y raro privilegio: en la Rusia de hoy, digo lo que considero justo y hago lo que considero necesario. Los canallas infames del Kremlin no tienen ning\u00fan poder sobre m\u00ed, aunque me hayan encerrado en un agujero.\u00bb<\/em><\/p>\n<p>Alex\u00e9i Navalni fue un hombre que luch\u00f3 hasta el final por la justicia y la libertad. Su legado perdurar\u00e1 como un testimonio de coraje, fe y compromiso con el bien com\u00fan.<\/p>\n<p><iframe loading=\"lazy\" title=\"No tengo miedo. No lo teng\u00e1is vosotros\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/4A4y7jAzO8Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-120068 alignnone\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3.jpg\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3.jpg 940w, https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3-300x251.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3-770x645.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3-500x419.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3-293x246.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/Luis-Herrea-campo-3-390x327.jpg 390w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alexei Navalny: Un legado de valent\u00eda y compromiso. El disidente que desaf\u00edo a Putin y al populismo occidental<\/p>\n","protected":false},"author":126,"featured_media":120071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[130],"tags":[47711,47708,47712,47713,47710,47715,20503,9929,47709,47714,4953,6057],"class_list":["post-120063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-activismo-politico","tag-alexei-navalny","tag-corrupcion-en-rusia","tag-democracia-en-rusia","tag-derechos-humanos-rusia","tag-legado-navalny","tag-libertad-de-expresion","tag-luis-herrera-campo","tag-oposicion-rusa","tag-presos-politicos","tag-trending-es","tag-vladimir-putin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Alexei Navalny: Un legado de valent\u00eda y compromiso. El disidente que desaf\u00edo a Putin y al populismo occidental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T07:30:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2094\" \/>\n\t<meta property=\"og:image:height\" content=\"1116\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Herrera Campo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Herrera Campo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/\"},\"author\":{\"name\":\"Luis Herrera Campo\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\"},\"headline\":\"No tengo miedo. No lo teng\u00e1is vosotros\",\"datePublished\":\"2025-02-27T07:30:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/\"},\"wordCount\":759,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/upscalemedia-transformed-1.jpeg\",\"keywords\":[\"activismo pol\u00edtico\",\"alexei navalny\",\"corrupci\u00f3n en rusia\",\"democracia en rusia\",\"derechos humanos rusia\",\"legado navalny\",\"libertad de expresi\u00f3n\",\"Luis Herrera Campo\",\"oposici\u00f3n rusa\",\"presos pol\u00edticos\",\"Trending\",\"Vladimir Putin\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/\",\"name\":\"No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/upscalemedia-transformed-1.jpeg\",\"datePublished\":\"2025-02-27T07:30:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/upscalemedia-transformed-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/upscalemedia-transformed-1.jpeg\",\"width\":2094,\"height\":1116},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/no-tengo-miedo-no-lo-tengais-vosotros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No tengo miedo. No lo teng\u00e1is vosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/8ba25804983f8e88d3d71c3808a804bc\",\"name\":\"Luis Herrera Campo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g\",\"caption\":\"Luis Herrera Campo\"},\"description\":\"Nac\u00ed en Burgos, donde vivo. Soy sacerdote del Opus Dei.\",\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@luisherreracampo\\\/featured\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/luis-herrera-campo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/","og_locale":"es_ES","og_type":"article","og_title":"No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi","og_description":"Alexei Navalny: Un legado de valent\u00eda y compromiso. El disidente que desaf\u00edo a Putin y al populismo occidental","og_url":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-02-27T07:30:30+00:00","og_image":[{"width":2094,"height":1116,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","type":"image\/jpeg"}],"author":"Luis Herrera Campo","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Luis Herrera Campo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/"},"author":{"name":"Luis Herrera Campo","@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc"},"headline":"No tengo miedo. No lo teng\u00e1is vosotros","datePublished":"2025-02-27T07:30:30+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/"},"wordCount":759,"image":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","keywords":["activismo pol\u00edtico","alexei navalny","corrupci\u00f3n en rusia","democracia en rusia","derechos humanos rusia","legado navalny","libertad de expresi\u00f3n","Luis Herrera Campo","oposici\u00f3n rusa","presos pol\u00edticos","Trending","Vladimir Putin"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/","url":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/","name":"No tengo miedo. No lo teng\u00e1is vosotros &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","datePublished":"2025-02-27T07:30:30+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","width":2094,"height":1116},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/no-tengo-miedo-no-lo-tengais-vosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"No tengo miedo. No lo teng\u00e1is vosotros"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/8ba25804983f8e88d3d71c3808a804bc","name":"Luis Herrera Campo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eac7d1a3c11ac010e320a821607af7cd107b34e1bdffe2f58efdf2b0a8d1c6e5?s=96&d=mm&r=g","caption":"Luis Herrera Campo"},"description":"Nac\u00ed en Burgos, donde vivo. Soy sacerdote del Opus Dei.","sameAs":["https:\/\/www.youtube.com\/@luisherreracampo\/featured"],"url":"https:\/\/exaudi.org\/es\/author\/luis-herrera-campo\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/upscalemedia-transformed-1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-vev","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/120063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/126"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=120063"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/120063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/120071"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=120063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=120063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=120063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}