{"id":119615,"date":"2025-02-22T11:00:31","date_gmt":"2025-02-22T10:00:31","guid":{"rendered":"https:\/\/exaudi.org\/?p=119615"},"modified":"2025-02-21T17:36:47","modified_gmt":"2025-02-21T16:36:47","slug":"reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/","title":{"rendered":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-119615-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/23-Febrero.mp3?_=1\" \/><a href=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/23-Febrero.mp3\">https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/23-Febrero.mp3<\/a><\/audio>\n<p>Mons. Enrique D\u00edaz D\u00edaz comparte con los lectores de Exaudi su reflexi\u00f3n sobre el\u00a0<a href=\"https:\/\/www.dominicos.org\/predicacion\/homilia\/23-2-2025\/lecturas\/\" target=\"_blank\" rel=\"noopener\">Evangelio de este domingo 23de febrero de 2025<\/a>, titulado: \u201cM\u00e1s all\u00e1 de la violencia\u201d<\/p>\n<p>***<\/p>\n<p>1 Samuel 26, 2. 7-9. 12-13.22-23: \u201cDavid no quiso atentar contra el ungido del Se\u00f1or\u201d<\/p>\n<p>Salmo 102: \u201cEl Se\u00f1or es compasivo y misericordioso\u201d<\/p>\n<p>1 Corintios 15, 45-49: \u201cFuimos semejantes al hombre terreno y seremos semejantes al hombre celestial\u201d<\/p>\n<p>San Lucas 6, 27-38: \u201cSean misericordiosos, como su Padre es misericordioso\u201d<\/p>\n<p>Semana a semana escuchamos noticias de violencia. No podemos ni debemos acostumbrarnos, sin embargo, est\u00e1n presenten en todos los \u00e1mbitos, desde los pa\u00edses en guerra o las violentas ejecuciones del narcotr\u00e1fico, hasta la cotidiana violencia en cada hogar que nos sorprende con grav\u00edsimos cr\u00edmenes y violaciones \u00bfC\u00f3mo terminar la violencia? Ciertamente no ser\u00e1 con m\u00e1s violencia, pero tampoco con la pasividad y la indiferencia.<\/p>\n<p>La Biblia dice: <em>\u201cAmar\u00e1s al Se\u00f1or, tu Dios, con todo tu coraz\u00f3n, con toda tu alma y con todas tus fuerzas\u2026 amar\u00e1s a tu pr\u00f3jimo como a ti mismo\u201d<\/em> Pero esta ley se fue quedando condicionada por la famosa ley del Tali\u00f3n del ojo por ojo y diente por diente que buscaba protecci\u00f3n para el m\u00e1s d\u00e9bil. Castigos, muros, leyes, buscan evitar los abusos, pero que al final se quedan en letras que no llegan a detener la violencia.<\/p>\n<p>Jes\u00fas propone otro camino. El reino de Dios no puede estar basado en la venganza, ni siquiera en la venganza limitada, sino en el principio del amor y el perd\u00f3n. El amor a los enemigos, que bien puede considerarse otra bienaventuranza, pues quienes lo practican son llamados por Jes\u00fas <em>\u201chijos del Alt\u00edsimo\u201d, <\/em>en este pasaje de San Lucas, como un fundamento important\u00edsimo de la paz. Y es cierto, la venganza y el odio no son diques que frenen la violencia; si no la frena el amor, no la podremos frenar jam\u00e1s.<\/p>\n<p>Un hombre anciano en sus \u00faltimos momentos confesaba que hab\u00eda vivido casi toda su vida, ahogado por el odio y la venganza. Un d\u00eda, de improviso, se decidi\u00f3 a perdonar: <em>\u201cFue como si hubiera nacido de nuevo. El odio es como una manzana con un gusano adentro. Nadie puede comer la manzana, pero lo podrido es la manzana. El odio pudre a quien lo lleva en su coraz\u00f3n\u201d<\/em> Si mir\u00e1ramos con detenimiento las guerras de la historia y las actuales, descubrir\u00edamos que m\u00e1s all\u00e1 de todo conflicto, fueron causadas por odios, por ego\u00edsmos y por venganzas que oscurecen la mente y entorpecen los sentidos. \u00bfA d\u00f3nde nos han llevado las guerras y la violencia? A Jes\u00fas, se le han unido grandes hombres y reformadores, anunciando con su vida y con sus obras que puede m\u00e1s el amor que el odio. Tenemos los grandes logros de Gandi, de Mart\u00edn Luther King y de tantos hombres y mujeres que han sido capaces de enfrentar con dignidad, con valent\u00eda, pero sin violencia, a quienes cometen injusticias.<\/p>\n<p>Un segundo principio que nos ofrece Cristo, consecuencia del primero, es <em>\u201cal que te golpee en una mejilla pres\u00e9ntale tambi\u00e9n la otra. Al que te arrebate el manto, entr\u00e9gale tambi\u00e9n el vestido\u2026\u201d <\/em>Estas propuestas de Jes\u00fas nos parecen hasta ingenuas y motivo de abusos de los poderosos. Pero tengamos en cuenta lo que acaba de decir en las bienaventuranzas.\u00a0 Se trata de ser mansos, pero no \u201cmensos\u201d. Jes\u00fas no intenta reducirnos a la pasividad, al conformismo o a la resignaci\u00f3n. \u00bfPor cu\u00e1nto tiempo utilizaron los poderosos la \u201cresignaci\u00f3n cristiana\u201d para acallar las voces que exig\u00edan sus derechos? No se trata de renunciar a nuestros derechos ni de callarnos frente a las injusticias, sino de renunciar a la violencia como \u00fanico medio para resolver las diferencias y los conflictos; y tambi\u00e9n, renunciar a nuestras comodidades o a nuestras prendas m\u00e1s preciadas para darlas a los que m\u00e1s las necesitan. En este sentido, Jes\u00fas supera el concepto de compartir que se ten\u00eda hasta el momento, pues ya no basta solo compartir el <em>\u201cpan con el hambriento&#8230;\u201d<\/em> sino entregarlo todo, incluso hasta la propia vida.<\/p>\n<p>El tercer principio que Jes\u00fas nos presenta va todav\u00eda m\u00e1s all\u00e1: si es revolucionario el anuncio de las bienaventuranzas, porque tienden a descubrir a Dios y su Reino como la \u00fanica riqueza y es, por tanto, capaz de poner en crisis todos los falsos valores que el ser humano se crea una y otra vez, se puede decir que es todav\u00eda m\u00e1s revolucionario el anuncio de un amor que ense\u00f1a a buscar al otro s\u00f3lo porque es el otro, prescindiendo del hecho que nos quiera o nos deteste, nos haga el bien o nos haga el mal:<em> \u201cSean misericordiosos, como su Padre es misericordioso\u2026<\/em> <em>y ser\u00e1n hijos del Alt\u00edsimo, porque \u00e9l es bueno hasta con los malos y los ingratos\u201d. <\/em>La misericordia se nos presenta como un elemento constitutivo del ser cristiano, por que lo es tambi\u00e9n de Dios.<\/p>\n<p>Debemos preguntarnos qu\u00e9 estamos haciendo realmente para acabar con la violencia y con el odio \u00bfHemos reflexionado alguna vez cu\u00e1n misericordiosos somos? Muchas veces confundimos la misericordia o la compasi\u00f3n con l\u00e1stima y eso no es cristiano, por que el que tiene l\u00e1stima inconscientemente se presenta como superior al otro; en cambio el que tiene misericordia establece una relaci\u00f3n de hermanos para encontrar juntos el camino del Se\u00f1or. Ser misericordioso es \u201cponer el coraz\u00f3n\u201d junto al coraz\u00f3n del otro. \u00bfPodremos hacerlo con aquellos que odiamos, especialmente cuando son cercanos a nosotros? Mucho m\u00e1s que perdonar, es <em>\u201camar al enemigo\u201d<\/em> lo que Jes\u00fas nos propone. En familia, en sociedad, m\u00e1s all\u00e1 de los malos entendidos que debemos superar, nos ofrece hoy Cristo un camino de reconciliaci\u00f3n. \u00bfQui\u00e9n est\u00e1 necesitado de mi perd\u00f3n y de mi amor? \u00bfPor qu\u00e9 considerar enemigo a mi propio hermano?<\/p>\n<p>As\u00ed nos dice Jes\u00fas en este pasaje: <em>\u201cTraten a los dem\u00e1s como quieran que los traten a ustedes\u2026 Porque con la misma medida con que midan, ser\u00e1n medidos\u201d<\/em> \u00bfMe gusta que me saluden, que me tomen en cuenta, que respeten mis derechos? Entonces debo yo empezar a hacerlo con los dem\u00e1s. \u00bfMe gustar\u00eda encontrar el verdadero perd\u00f3n y poder seguir siendo hermano de los dem\u00e1s? Entonces yo debo otorgar el perd\u00f3n y amar \u201cincluso a los enemigos\u201d. Y la raz\u00f3n de fondo nos la da Jes\u00fas: \u201cPara parecerte a tu Padre Celestial\u201d. Es el sue\u00f1o de Jes\u00fas: que todos podamos vivir como hermanos pareci\u00e9ndonos a nuestro Padre Celestial.<\/p>\n<p><em>Conc\u00e9denos, Se\u00f1or, ser d\u00f3ciles al Esp\u00edritu y cambiar las armas por instrumentos de paz, el odio por amor y construir un mundo nuevo conforme a tus designios de Padre Misericordioso. Am\u00e9n.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VII Domingo Ordinario<\/p>\n","protected":false},"author":25,"featured_media":119616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[96,74],"tags":[30419,46783,46797,46800,46800,5654,26644,20343,1372,28281,46791,35486,46796,46792,25344,46795,46793,46799,46798,46802,414,46789,46801,26465,4953,19540,46790,46794],"class_list":["post-119615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad","category-iglesia-y-mundo","tag-amar-al-projimo","tag-amor-a-los-enemigos","tag-biblia-y-violencia","tag-construir-la-paz","tag-enrique-diaz","tag-ensenanza-de-jesus","tag-espiritualidad-catolica","tag-evangelio","tag-evangelio-de-san-lucas","tag-evangelio-del-23-de-febrero-de-2025","tag-fe-y-misericordia","tag-jesus-y-la-reconciliacion","tag-mas-alla-de-la-violencia","tag-mensaje-cristiano","tag-misericordia-cristiana","tag-mons-enrique-diaz-diaz","tag-paz-en-la-familia","tag-perdon-y-amor","tag-reconciliacion-y-amor","tag-reflexion","tag-reflexion-de-mons-enrique-diaz","tag-reflexion-dominical","tag-superar-el-odio","tag-trending-es","tag-valores-cristianos","tag-vii-domingo-ordinario","tag-violencia-y-perdon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"VII Domingo Ordinario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-22T10:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"968\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Enrique D\u00edaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrique D\u00edaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/\"},\"author\":{\"name\":\"Enrique D\u00edaz\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"headline\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia\",\"datePublished\":\"2025-02-22T10:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/\"},\"wordCount\":1200,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/father-2903781_1280.webp?fit=1280%2C968&ssl=1\",\"keywords\":[\"amar al pr\u00f3jimo\",\"amor a los enemigos\",\"Biblia y violencia\",\"construir la paz\",\"construir la paz\",\"Enrique D\u00edaz\",\"ense\u00f1anza de Jes\u00fas\",\"espiritualidad cat\u00f3lica\",\"Evangelio\",\"Evangelio de San Lucas\",\"Evangelio del 23 de febrero de 2025\",\"Fe y misericordia\",\"Jes\u00fas y la reconciliaci\u00f3n\",\"M\u00e1s all\u00e1 de la violencia\",\"mensaje cristiano\",\"misericordia cristiana\",\"Mons. Enrique D\u00edaz D\u00edaz\",\"paz en la familia\",\"perd\u00f3n y amor\",\"reconciliaci\u00f3n y amor\",\"Reflexi\u00f3n\",\"Reflexi\u00f3n de Mons. Enrique D\u00edaz\",\"reflexi\u00f3n dominical\",\"superar el odio\",\"Trending\",\"valores cristianos\",\"VII Domingo Ordinario\",\"violencia y perd\u00f3n\"],\"articleSection\":[\"Espiritualidad\",\"Iglesia y Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/\",\"name\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/father-2903781_1280.webp?fit=1280%2C968&ssl=1\",\"datePublished\":\"2025-02-22T10:00:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/father-2903781_1280.webp?fit=1280%2C968&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/father-2903781_1280.webp?fit=1280%2C968&ssl=1\",\"width\":1280,\"height\":968,\"caption\":\"Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\",\"name\":\"Enrique D\u00edaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"caption\":\"Enrique D\u00edaz\"},\"description\":\"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/enriquediaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/","og_locale":"es_ES","og_type":"article","og_title":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi","og_description":"VII Domingo Ordinario","og_url":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2025-02-22T10:00:31+00:00","og_image":[{"width":1280,"height":968,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp","type":"image\/webp"}],"author":"Enrique D\u00edaz","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Enrique D\u00edaz","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/"},"author":{"name":"Enrique D\u00edaz","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"headline":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia","datePublished":"2025-02-22T10:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/"},"wordCount":1200,"image":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp?fit=1280%2C968&ssl=1","keywords":["amar al pr\u00f3jimo","amor a los enemigos","Biblia y violencia","construir la paz","construir la paz","Enrique D\u00edaz","ense\u00f1anza de Jes\u00fas","espiritualidad cat\u00f3lica","Evangelio","Evangelio de San Lucas","Evangelio del 23 de febrero de 2025","Fe y misericordia","Jes\u00fas y la reconciliaci\u00f3n","M\u00e1s all\u00e1 de la violencia","mensaje cristiano","misericordia cristiana","Mons. Enrique D\u00edaz D\u00edaz","paz en la familia","perd\u00f3n y amor","reconciliaci\u00f3n y amor","Reflexi\u00f3n","Reflexi\u00f3n de Mons. Enrique D\u00edaz","reflexi\u00f3n dominical","superar el odio","Trending","valores cristianos","VII Domingo Ordinario","violencia y perd\u00f3n"],"articleSection":["Espiritualidad","Iglesia y Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/","url":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/","name":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp?fit=1280%2C968&ssl=1","datePublished":"2025-02-22T10:00:31+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp?fit=1280%2C968&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp?fit=1280%2C968&ssl=1","width":1280,"height":968,"caption":"Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-mas-alla-de-la-violencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: M\u00e1s all\u00e1 de la violencia"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d","name":"Enrique D\u00edaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","caption":"Enrique D\u00edaz"},"description":"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.","url":"https:\/\/exaudi.org\/es\/author\/enriquediaz\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2025\/02\/father-2903781_1280.webp?fit=1280%2C968&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-v7h","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/119615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=119615"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/119615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/119616"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=119615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=119615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=119615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}