{"id":117455,"date":"2025-01-23T09:27:33","date_gmt":"2025-01-23T08:27:33","guid":{"rendered":"https:\/\/exaudi.org\/?p=117455"},"modified":"2025-01-23T10:46:33","modified_gmt":"2025-01-23T09:46:33","slug":"el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/","title":{"rendered":"El Papa: Necesitamos superar una mentalidad clerical y chovinista"},"content":{"rendered":"<p>Este mi\u00e9rcoles 22 de enero de 2025, el Santo Padre Francisco recibi\u00f3 en audiencia a los miembros de la Fundaci\u00f3n Hilton, una organizaci\u00f3n estadounidense sin fines de lucro que colabora con algunos Dicasterios del Vaticano para brindar oportunidades de formaci\u00f3n, crecimiento y estudio a mujeres religiosas. \u201cSe ha invertido poco en esto, menos que con el clero porque se le considera de &#8216;segunda clase&#8217;. Necesitamos superar una mentalidad clerical y chovinista\u00bb.<\/p>\n<p>El Papa les dirigi\u00f3 las siguientes palabras de saludo:<\/p>\n<p>***<\/p>\n<h3><strong>Palabras del Papa<\/strong><\/h3>\n<p><i>S<\/i><i>e\u00f1oras y se\u00f1ores, bienvenidos, buenos d\u00edas y gracias por esta visita.<\/i><\/p>\n<p>Estoy encantado de reunirme con ustedes, que forman el consejo de la Fundaci\u00f3n Conrad Hilton.<\/p>\n<p>La misi\u00f3n de promover la dignidad humana es urgente en un momento en que el n\u00famero de pobres y excluidos sigue aumentando. Es curioso&#8230; Ustedes han elegido no quedarse en la ventana, sino comprometerse personalmente con pasi\u00f3n y compasi\u00f3n, como el buen samaritano. Esta par\u00e1bola de Jes\u00fas nos ense\u00f1a a asumir la fragilidad de los dem\u00e1s, a estar cerca de ellos y a levantar a los que han ca\u00eddo, por el bien de todos (cf. Carta Enc\u00edclica,\u00a0<i><a href=\"https:\/\/www.vatican.va\/content\/francesco\/es\/encyclicals\/documents\/papa-francesco_20201003_enciclica-fratelli-tutti.html#67\">Fratelli tutti<\/a><\/i>, 67). No olviden que s\u00f3lo en una ocasi\u00f3n y en un acto de la historia es l\u00edcito mirar una persona de arriba a abajo, una sola ocasi\u00f3n: para ayudarla a levantarse. Por lo dem\u00e1s, no se puede mirar a una persona por encima del hombro. \u00danicamente para ayudarla a levantarse, no lo olviden&#8230;. Siempre.<\/p>\n<p>Su Fundaci\u00f3n ha demostrado c\u00f3mo la generosidad y el compromiso pueden transformar la vida de quienes se encuentran en situaciones de vulnerabilidad. El servicio gratuito en los campos de la educaci\u00f3n, la sanidad, la ayuda a los refugiados y el alivio de la pobreza es un testimonio, un testimonio concreto de amor y compasi\u00f3n. No olviden esta palabra: compasi\u00f3n, &#8216;<i>sufrir con<\/i>&#8216;. Dios es compasivo, Dios nos tiende la mano y sufre con nosotros. Y la compasi\u00f3n no es lanzar una moneda a la mano de la otra persona sin mirarla a los ojos. No. La compasi\u00f3n es acercarse y &#8216;\u00a0<i>sufrir con<\/i>&#8216;. Que no se le olviden esta palabra:\u00a0<i>compasi\u00f3n<\/i>.<\/p>\n<p>Su fundador, Conrad Nicholson Hilton, les leg\u00f3 su sue\u00f1o, que anima los proyectos de la Fundaci\u00f3n. Entre ellos hay uno en el que ustedes son muy activos: el de apoyar a las monjas. Conrad Hilton ten\u00eda en gran estima a las monjas y en su testamento pidi\u00f3 a la Fundaci\u00f3n que las apoyara en su misi\u00f3n de servir a los m\u00e1s pobres y a los \u00faltimos. Una vez, me dijo una persona -era agn\u00f3stica- acab\u00f3 en el hospital y las monjitas le cuidaron&#8230; Se convirti\u00f3 gracias a eso. Y dijo: qu\u00e9 ser\u00eda de la Iglesia sin las monjitas&#8230; \u00a1es hermoso! Y ustedes lo hacen con fidelidad y creatividad, sobre todo para la formaci\u00f3n y el cuidado de las hermanas mayores. En algunos pa\u00edses son\u00a0<i>ya ancianitas<\/i>, pero no hay que enviarlas al hospicio, no&#8230; Recuerdo una vez, en Argentina, en una congregaci\u00f3n -de la que yo ten\u00eda una hermana de origen italiano- vino una provincial y dijo: \u00ab\u00a1No! A los 70 a\u00f1os, \u00a1fuera!\u00bb, y las hermanas se mor\u00edan de tristeza&#8230; Las hermanas deben trabajar hasta el final, como puedan, hasta el final. Y si no hacen esto, hacen lo otro. Aqu\u00ed tenemos a una que siempre ha trabajado con los pobres. Es anciana, pero a\u00fan conduce, y la dejan conducir, y as\u00ed se siente \u00fatil. Por favor, \u00a1las \u00abmonjitas\u00bb siempre con la gente! S\u00e9 que colaboran con algunos dicasterios vaticanos para dar oportunidades a las hermanas de crecer en profesionalidad y trabajo misionero. Gracias.<\/p>\n<p>Se ha invertido poco en esto, mucho menos que en la formaci\u00f3n del clero. Es cierto, porque se piensa que las monjas, y tambi\u00e9n las mujeres, son \u00abde segunda clase\u00bb. Se piensa esto&#8230; No se olviden que desde el d\u00eda del Jard\u00edn del Ed\u00e9n son ellas las que mandan&#8230; \u00a1Las mujeres mandan! Es importante que las hermanas puedan estudiar y formarse. El trabajo en las fronteras, en las periferias, entre los \u00faltimos, necesita personas formadas y competentes. Y, atenci\u00f3n, la misi\u00f3n de las hermanas es servir a los \u00faltimos, y no ser siervas de alguien. Esto debe terminar, y ustedes como Fundaci\u00f3n est\u00e1n ayudando a sacar a la Iglesia de esta mentalidad clericalista.<\/p>\n<p>Pero tambi\u00e9n debo a\u00f1adir otra cosa: a menudo nos quejamos de que no hay suficientes monjas en puestos de responsabilidad, en las di\u00f3cesis, la Curia y las universidades. Esto es cierto. Por un lado, es cierto, necesitamos superar una mentalidad clerical y machista. Gracias a Dios, ahora tenemos un prefecto en la Curia, del Dicasterio para los Religiosos. Tenemos una vicegobernadora del Estado Vaticano que ser\u00e1 gobernadora en marzo. Tenemos tres monjas en el\u00a0<i>equipo de<\/i> los que eligen a los obispos, y que dan el voto. Tenemos a la subsecretaria de monse\u00f1or Piccinotti en la A.P.S.A.: una monja que tiene dos licenciaturas en econom\u00eda. Gracias a Dios, las monjas est\u00e1n saliendo adelante y saben hacer las cosas mejor que los hombres. Es as\u00ed&#8230; porque tienen esa capacidad de hacer las cosas, las mujeres y las monjitas. Tambi\u00e9n he o\u00eddo a obispos decir: Me gustar\u00eda nombrar monjas en algunos cargos diocesanos, pero sus superioras no las dejan ir. No, por favor, d\u00e9jenlas que vayan. As\u00ed que les digo a las superioras: sean generosas, tengan el respiro de la Iglesia universal y de una misi\u00f3n que va m\u00e1s all\u00e1 de los confines de su Instituto.<\/p>\n<p>Queridos amigos, gracias por su incansable trabajo y servicio. \u00a1Gracias! Juntos podemos construir un mundo en el que cada persona, sea cual sea su origen o su situaci\u00f3n, pueda vivir con dignidad. Juntos podemos ayudar a encender la esperanza en los corazones de quienes se sienten solos y abandonados. Compasi\u00f3n, cercan\u00eda, ternura: no se olviden de estas tres palabras. Compasi\u00f3n, cercan\u00eda, ternura: estos son los tres atributos de Dios. Dios es compasivo, Dios es cercano, Dios es tierno. Sue\u00f1o con un mundo en el que los descartados, los excluidos, los marginados puedan ser los protagonistas de un cambio social que tanto necesitamos, para vivir como hermanos y hermanas.<\/p>\n<p>Que Dios los bendiga y que la Virgen los proteja. Y, por favor, recen por m\u00ed. Ahora, as\u00ed sentados, les doy la bendici\u00f3n. Gracias.<br \/>\n_____________________________<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fundaci\u00f3n Conrad Hilton<\/p>\n","protected":false},"author":15,"featured_media":117456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[124,68],"tags":[42013,158],"class_list":["post-117455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discursos","category-leon-xiv","tag-fundacion-hilton","tag-papa-francisco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Fundaci\u00f3n Conrad Hilton\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T08:27:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T09:46:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"El Papa: Necesitamos superar una mentalidad clerical y chovinista\",\"datePublished\":\"2025-01-23T08:27:33+00:00\",\"dateModified\":\"2025-01-23T09:46:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/\"},\"wordCount\":1117,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg\",\"keywords\":[\"Fundaci\u00f3n Hilton\",\"papa francisco\"],\"articleSection\":[\"Discursos\",\"Le\u00f3n XIV\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/\",\"name\":\"El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg\",\"datePublished\":\"2025-01-23T08:27:33+00:00\",\"dateModified\":\"2025-01-23T09:46:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa: Necesitamos superar una mentalidad clerical y chovinista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/","og_locale":"es_ES","og_type":"article","og_title":"El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi","og_description":"Fundaci\u00f3n Conrad Hilton","og_url":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2025-01-23T08:27:33+00:00","article_modified_time":"2025-01-23T09:46:33+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"El Papa: Necesitamos superar una mentalidad clerical y chovinista","datePublished":"2025-01-23T08:27:33+00:00","dateModified":"2025-01-23T09:46:33+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/"},"wordCount":1117,"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","keywords":["Fundaci\u00f3n Hilton","papa francisco"],"articleSection":["Discursos","Le\u00f3n XIV"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/","url":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/","name":"El Papa: Necesitamos superar una mentalidad clerical y chovinista &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","datePublished":"2025-01-23T08:27:33+00:00","dateModified":"2025-01-23T09:46:33+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/el-papa-necesitamos-superar-una-mentalidad-clerical-y-chovinista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Papa: Necesitamos superar una mentalidad clerical y chovinista"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2025\/01\/cq5dam.web_.800.800-2025-01-23T091204.489.jpeg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-uyr","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/117455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=117455"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/117455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/117456"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=117455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=117455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=117455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}