{"id":114739,"date":"2024-12-12T08:45:43","date_gmt":"2024-12-12T07:45:43","guid":{"rendered":"https:\/\/exaudi.org\/?p=114739"},"modified":"2024-12-11T13:49:10","modified_gmt":"2024-12-11T12:49:10","slug":"cardenal-arizmendi-de-que-sirve-decirse-catolico","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/","title":{"rendered":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?"},"content":{"rendered":"<p>El\u00a0<a href=\"https:\/\/exaudi.org\/es\/author\/felipearizmendi\/\" target=\"_blank\" rel=\"noopener\">cardenal Felipe Arizmendi<\/a>, obispo em\u00e9rito de San Crist\u00f3bal de Las Casas y responsable de la Doctrina de la Fe en la\u00a0<a href=\"https:\/\/www.cem.org.mx\/\" target=\"_blank\" rel=\"noopener\">Conferencia del Episcopado Mexicano (CEM)<\/a>, ofrece a los lectores de Exaudi su art\u00edculo semanal.<\/p>\n<p><iframe title=\"Spotify Embed: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/1VB908p6iMl4IHUUfp6esy?si=db4dda618eff4feb&#038;utm_source=oembed\"><\/iframe><\/p>\n<h3><strong>MIRAR<\/strong><\/h3>\n<p>Este 8 de diciembre, se cumpli\u00f3 un a\u00f1o de que los campesinos de Texcapilla, muy cerca de mi pueblo natal, se organizaron y mataron al grupo criminal de diez personas que lleg\u00f3 con armas de alto poder y que les exig\u00eda <em>el cobro de piso <\/em>por sus cultivos de habas, ch\u00edcharos, avena, frijol y ma\u00edz. No pudieron soportar que les quisieran cobrar m\u00e1s y m\u00e1s. Mataron tambi\u00e9n a su l\u00edder, apodado <em>El Payaso, <\/em>con quien yo, circunstancialmente, hab\u00eda hablado meses antes. Cuando lo vi en mi pueblo, me identifiqu\u00e9 y pedir hablar con \u00e9l. Estaba armado y rodeado de sus pistoleros. Su esposa, al escuchar que yo era obispo, me pidi\u00f3 que insistiera a su marido que ya bautizaran a dos de sus ni\u00f1os, una de nueve a\u00f1os y otro beb\u00e9. Muy <em>cat\u00f3lico<\/em>, s\u00ed quer\u00eda bautizarlos, pero en su pueblo de origen, m\u00e1s al sur del Estado de M\u00e9xico. Intent\u00e9 servirme de este su deseo para iniciar un proceso pastoral e insistirle que cambiara de vida. Ya no supe si los bautizaron, porque al poco tiempo lo mataron. \u00bfDe qu\u00e9 le serv\u00eda decirse cat\u00f3lico y que sus hijos fueran bautizados? Ciertamente no era por una fe madura en Jes\u00fas, sino por simple tradici\u00f3n. No le importaba tanto Dios, pues su dios era el dinero que exprim\u00eda a los m\u00e1s pobres, a los m\u00e1s indefensos, como son la mayor\u00eda de nuestros campesinos.<\/p>\n<p>El l\u00edder de otro grupo criminal, de la misma llamada <em>Familia Michoacana, <\/em>tiene a sus ni\u00f1as en la catequesis parroquial, prepar\u00e1ndose a la Primera Comuni\u00f3n. Los m\u00e1ximos l\u00edderes de otros grupos armados se consideran cat\u00f3licos. Algo semejante pasa con pol\u00edticos, que oficialmente son cat\u00f3licos, pero su dios es el poder, el dinero, y no les importa ir a Misa los domingos, no leen la Biblia, oran s\u00f3lo por sus intereses; pero eso s\u00ed, si una autoridad superior les pide estar en una reuni\u00f3n, organizar un mitin u otra actividad, se someten a esas disposiciones y no les importa su religi\u00f3n; saben que, si no acatan deseos u \u00f3rdenes superiores, se exponen a perder su puesto y a no ascender m\u00e1s en el partido o en el gobierno. Su dios es el poder y el dinero. Lo mismo se podr\u00eda decir en muchos otros casos. Festejan a la Virgen de Guadalupe, esperan las vacaciones y el aguinaldo de Navidad, pero seguir a Jes\u00fas no les interesa. Otros se declaran creyentes, pero no dejan el alcohol y las drogas, son infieles en su matrimonio, no pagan lo justo a sus trabajadores, viven en excesos de toda \u00edndole. Se dicen cat\u00f3licos, y hasta llevan una medalla o un Crucifijo al pecho; pero eso \u00bfde qu\u00e9 les sirve?<\/p>\n<p>En sentido contrario, \u00a1son much\u00edsimos m\u00e1s los que son de verdad cat\u00f3licos! No s\u00f3lo van a Misa los domingos y hacen oraci\u00f3n, sino que son justos y a nadie perjudican; comparten sus bienes; mantienen unida su familia y son fieles en su matrimonio; educan a sus hijos conforme a la fe; no se averg\u00fcenzan de sus creencias religiosas; sirven a la comunidad; son ap\u00f3stoles entregados hasta el sacrificio. Pareciera que abunda m\u00e1s lo malo, pues los noticieros resaltan m\u00e1s las notas rojas; pero en la vida ordinaria son m\u00e1s numerosos los que son aut\u00e9nticamente cat\u00f3licos.<\/p>\n<h3><strong>DISCERNIR<\/strong><\/h3>\n<p>Los obispos latinoamericanos, en el Documento de Puebla, despu\u00e9s de la primera visita del Papa San Juan Pablo II a nuestra patria, en enero de 1979, expresaron algo sobre la injusticia social en nuestro continente, pero que se aplica a nuestra realidad marcada por la violencia y por la fuerza de los grupos armados. Dijeron:<em> \u201c<\/em><em>Nos preocupan las angustias de todos los miembros del pueblo cualquiera sea su condici\u00f3n social: su soledad, sus problemas familiares, en no pocos, la carencia del sentido de la vida; especialmente queremos compartir hoy las que brotan de su pobreza. Vemos, a la luz de la fe, como un esc\u00e1ndalo y una contradicci\u00f3n con el ser cristiano, la creciente brecha entre ricos y pobres. El lujo de unos pocos se convierte en insulto contra la miseria de las grandes masas. Esto es contrario al plan del Creador y al honor que se le debe. En esta angustia y dolor, la Iglesia discierne una situaci\u00f3n de pecado social, de gravedad tanto mayor por darse en pa\u00edses que se llaman cat\u00f3licos\u201d<\/em> (DP 27-28).<\/p>\n<p>Por nuestra parte, los obispos mexicanos, en el <em>Proyecto Global de Pastoral 2031+2033, <\/em>expresamos:<em> \u201c<\/em><em>En toda esta transformaci\u00f3n de pensamiento y de vida, la religi\u00f3n ha sufrido tambi\u00e9n un fuerte impacto: transformaci\u00f3n radical en la forma de asumir la fe de los creyentes, p\u00e9rdida del fervor original, desprecio por las instituciones, ambiente relativista e individualista y un secularismo que ha reducido la fe al \u00e1mbito de lo privado y de lo \u00edntimo. Dentro de este fen\u00f3meno religioso, la violencia ha alcanzado niveles preocupantes y dolorosos para el mundo entero\u201d <\/em>(PGP 36)<em>.<\/em><\/p>\n<p><em>\u201cEl panorama social se ha ido ensombreciendo paulatinamente por el fortalecimiento alarmante del crimen organizado, corrompiendo la mente y el coraz\u00f3n de personas y autoridades.\u00a0 La introducci\u00f3n de una narco-cultura en nuestra sociedad mexicana, de conseguir dinero r\u00e1pido, f\u00e1cil y de cualquier forma, ha venido a da\u00f1ar profundamente la mente de muchas personas, a quienes no les importa matar, robar, extorsionar, secuestrar o hacer cualquier cosa con tal de conseguir sus objetivos. Esta sociedad que tendr\u00eda que ofrecer a todos los ciudadanos las condiciones necesarias para vivir con dignidad, est\u00e1 da\u00f1ada y es necesario que todos como miembros de ella tomemos conciencia de esta realidad y nos hagamos responsables, para que pueda cumplir como un espacio de vida digna para todos sus miembros\u201d <\/em>(PGP 57).<\/p>\n<h3><strong>ACTUAR<\/strong><\/h3>\n<p>Para que haya paz familiar y social, para que festejemos dignamente a la Virgen de Guadalupe, para que celebremos aut\u00e9nticamente la Navidad, esforc\u00e9monos por vivir con fidelidad nuestra fe cat\u00f3lica; evitemos todo aquello que contradiga la Palabra de Dios; en resumen, respet\u00e9monos y am\u00e9monos como hermanas y hermanos.<\/p>\n<p><iframe title=\"\u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/XAd-WXpLHKw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La contradicci\u00f3n entre la fe y la vida de quienes se dicen cat\u00f3licos sin vivir conforme a los valores cristianos<\/p>\n","protected":false},"author":24,"featured_media":114740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_wpcom_ai_launchpad_first_post":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[3727,413,8422,8766,8975,33291,36791,17563,2419,449,1767,36789,4700,1646,36792,36788,36787,36790,725,589],"class_list":["post-114739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-cardenal-felipe-arizmendi","tag-cardenal-felipe-arizmendi-esquivel","tag-catolicismo","tag-crimen-organizado","tag-doctrina-social","tag-educacion-cristiana","tag-fe-autentica","tag-fe-cristiana","tag-featured","tag-iglesia-catolica","tag-justicia-social","tag-narco-cultura","tag-navidad","tag-pobreza","tag-pobreza-en-mexico","tag-proyecto-global-pastoral-20312033","tag-puebla-1979","tag-transformacion-religiosa","tag-violencia","tag-virgen-de-guadalupe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"La contradicci\u00f3n entre la fe y la vida de quienes se dicen cat\u00f3licos sin vivir conforme a los valores cristianos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T07:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cardenal Felipe Arizmendi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cardenal Felipe Arizmendi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/\"},\"author\":{\"name\":\"Cardenal Felipe Arizmendi\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\"},\"headline\":\"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?\",\"datePublished\":\"2024-12-12T07:45:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/\"},\"wordCount\":1123,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1\",\"keywords\":[\"Cardenal Felipe Arizmendi\",\"Cardenal Felipe Arizmendi Esquivel\",\"Catolicismo\",\"Crimen organizado\",\"Doctrina Social\",\"educaci\u00f3n cristiana\",\"fe aut\u00e9ntica\",\"Fe cristiana\",\"Featured\",\"Iglesia cat\u00f3lica\",\"Justicia Social\",\"narco-cultura\",\"navidad\",\"Pobreza\",\"pobreza en M\u00e9xico\",\"Proyecto Global Pastoral 2031+2033\",\"Puebla 1979\",\"transformaci\u00f3n religiosa\",\"violencia\",\"Virgen de Guadalupe\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/\",\"name\":\"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2024-12-12T07:45:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/cardenal-arizmendi-de-que-sirve-decirse-catolico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c7d223f87e58f1105d044d8da1439102\",\"name\":\"Cardenal Felipe Arizmendi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g\",\"caption\":\"Cardenal Felipe Arizmendi\"},\"description\":\"Nacido en Chiltepec el 1 de mayo de 1940. Estudi\u00f3 Humanidades y Filosof\u00eda en el Seminario de Toluca, de 1952 a 1959. Curs\u00f3 la Teolog\u00eda en la Universidad Pontificia de Salamanca, Espa\u00f1a, de 1959 a 1963, obteniendo la licenciatura en Teolog\u00eda Dogm\u00e1tica. Por su cuenta, se especializ\u00f3 en Liturgia. Fue ordenado sacerdote el 25 de agosto de 1963 en Toluca. Sirvi\u00f3 como Vicario Parroquial en tres parroquias por tres a\u00f1os y medio y fue p\u00e1rroco de una comunidad ind\u00edgena otom\u00ed, de 1967 a 1970. Fue Director Espiritual del Seminario de Toluca por diez a\u00f1os, y Rector del mismo de 1981 a 1991. El 7 de marzo de 1991, fue ordenado obispo de la di\u00f3cesis de Tapachula, donde estuvo hasta el 30 de abril del a\u00f1o 2000. El 1 de mayo del 2000, inici\u00f3 su ministerio episcopal como XLVI obispo de la di\u00f3cesis de San Crist\u00f3bal de las Casas, Chiapas, una de las di\u00f3cesis m\u00e1s antiguas de M\u00e9xico, erigida en 1539; all\u00ed sirvi\u00f3 por casi 18 a\u00f1os. Ha ocupado diversos cargos en la Conferencia del Episcopado Mexicano y en el CELAM. El 3 de noviembre de 2017, el Papa Francisco le acept\u00f3, por edad, su renuncia al servicio episcopal en esta di\u00f3cesis, que entreg\u00f3 a su sucesor el 3 de enero de 2018. Desde entonces, reside en la ciudad de Toluca. Desde 1979, escribe art\u00edculos de actualidad en varios medios religiosos y civiles. Es autor de varias publicaciones.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/felipearizmendi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/","og_locale":"es_ES","og_type":"article","og_title":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi","og_description":"La contradicci\u00f3n entre la fe y la vida de quienes se dicen cat\u00f3licos sin vivir conforme a los valores cristianos","og_url":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2024-12-12T07:45:43+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg","type":"image\/jpeg"}],"author":"Cardenal Felipe Arizmendi","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Cardenal Felipe Arizmendi","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/"},"author":{"name":"Cardenal Felipe Arizmendi","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102"},"headline":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?","datePublished":"2024-12-12T07:45:43+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/"},"wordCount":1123,"image":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1","keywords":["Cardenal Felipe Arizmendi","Cardenal Felipe Arizmendi Esquivel","Catolicismo","Crimen organizado","Doctrina Social","educaci\u00f3n cristiana","fe aut\u00e9ntica","Fe cristiana","Featured","Iglesia cat\u00f3lica","Justicia Social","narco-cultura","navidad","Pobreza","pobreza en M\u00e9xico","Proyecto Global Pastoral 2031+2033","Puebla 1979","transformaci\u00f3n religiosa","violencia","Virgen de Guadalupe"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/","url":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/","name":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico? &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1","datePublished":"2024-12-12T07:45:43+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/cardenal-arizmendi-de-que-sirve-decirse-catolico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Cardenal Arizmendi: \u00bfDe qu\u00e9 sirve decirse cat\u00f3lico?"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c7d223f87e58f1105d044d8da1439102","name":"Cardenal Felipe Arizmendi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ffc5520d896b86d39346168903de33a17ef0f23d16de0ff45062c1ff422ed2f?s=96&d=mm&r=g","caption":"Cardenal Felipe Arizmendi"},"description":"Nacido en Chiltepec el 1 de mayo de 1940. Estudi\u00f3 Humanidades y Filosof\u00eda en el Seminario de Toluca, de 1952 a 1959. Curs\u00f3 la Teolog\u00eda en la Universidad Pontificia de Salamanca, Espa\u00f1a, de 1959 a 1963, obteniendo la licenciatura en Teolog\u00eda Dogm\u00e1tica. Por su cuenta, se especializ\u00f3 en Liturgia. Fue ordenado sacerdote el 25 de agosto de 1963 en Toluca. Sirvi\u00f3 como Vicario Parroquial en tres parroquias por tres a\u00f1os y medio y fue p\u00e1rroco de una comunidad ind\u00edgena otom\u00ed, de 1967 a 1970. Fue Director Espiritual del Seminario de Toluca por diez a\u00f1os, y Rector del mismo de 1981 a 1991. El 7 de marzo de 1991, fue ordenado obispo de la di\u00f3cesis de Tapachula, donde estuvo hasta el 30 de abril del a\u00f1o 2000. El 1 de mayo del 2000, inici\u00f3 su ministerio episcopal como XLVI obispo de la di\u00f3cesis de San Crist\u00f3bal de las Casas, Chiapas, una de las di\u00f3cesis m\u00e1s antiguas de M\u00e9xico, erigida en 1539; all\u00ed sirvi\u00f3 por casi 18 a\u00f1os. Ha ocupado diversos cargos en la Conferencia del Episcopado Mexicano y en el CELAM. El 3 de noviembre de 2017, el Papa Francisco le acept\u00f3, por edad, su renuncia al servicio episcopal en esta di\u00f3cesis, que entreg\u00f3 a su sucesor el 3 de enero de 2018. Desde entonces, reside en la ciudad de Toluca. Desde 1979, escribe art\u00edculos de actualidad en varios medios religiosos y civiles. Es autor de varias publicaciones.","url":"https:\/\/exaudi.org\/es\/author\/felipearizmendi\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-tQD","jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/12\/pexels-engin-deniz-kopan-1829710573-29718572-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/114739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=114739"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/114739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/114740"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=114739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=114739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=114739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}