{"id":113478,"date":"2024-11-24T19:22:19","date_gmt":"2024-11-24T18:22:19","guid":{"rendered":"https:\/\/exaudi.org\/?p=113478"},"modified":"2024-11-24T19:23:55","modified_gmt":"2024-11-24T18:23:55","slug":"reflexion-de-mons-enrique-diaz-cristo-rey","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/","title":{"rendered":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-113478-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/24-Noviembre.mp3?_=1\" \/><a href=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/24-Noviembre.mp3\">https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/24-Noviembre.mp3<\/a><\/audio>\n<p>Mons. Enrique D\u00edaz D\u00edaz comparte con los lectores de Exaudi su reflexi\u00f3n sobre el\u00a0Evangelio de este <a href=\"https:\/\/www.dominicos.org\/predicacion\/evangelio-del-dia\/hoy\/\" target=\"_blank\" rel=\"noopener\">Domingo 24 de noviembre, de 2024<\/a>.<\/p>\n<p>***<\/p>\n<p>Daniel 7, 13-14: \u201cSu poder es eterno\u201d<\/p>\n<p>Salmo 92: \u201cSe\u00f1or, t\u00fa eres nuestro rey\u201d<\/p>\n<p>Apocalipsis 1, 5-8: \u201cEl soberano de los reyes de la tierra ha hecho de nosotros un reino de sacerdotes para su Dios y Padre\u201d<\/p>\n<p>San Juan 18, 33-37: \u201cT\u00fa lo has dicho. Soy rey\u201d<\/p>\n<p>En el \u00faltimo domingo del a\u00f1o celebramos una fiesta que da sentido y culmen a todo este tiempo: Cristo Rey. Pero \u00bfde qu\u00e9 rey se trata? Juan parece darnos la respuesta. El relato del proceso de Jes\u00fas ante Pilato tiene un gran relieve en el evangelio de Juan. La reflexi\u00f3n sobre la realeza est\u00e1 presente en todo el episodio hasta llegar a la declaraci\u00f3n de Pilato a los jud\u00edos: \u201c\u00a1Aqu\u00ed tienen a su rey!\u201d que junto a la declaraci\u00f3n de que es \u201cHijo de Dios\u201d, son las dos causas que se aducen para su condena. De hecho, se confrontan dos estilos de realeza: por una parte, la pol\u00edtico\/militar que sostiene la ideolog\u00eda del imperio romano, y por otra, la realeza que los jud\u00edos esperaban como venida de un mes\u00edas que deber\u00eda liberarlos del yugo. Jes\u00fas no se puede adaptar a ninguna de las dos. La fiesta de Cristo Rey nos ofrece un concepto de realeza muy diferente a lo que esperar\u00edamos humanamente. La realeza de Jes\u00fas, como aparece en este texto, es de otra forma, a tal grado que, aunque es el condenado y golpeado, sigue apareciendo como el verdadero rey frente a la caricatura de poder que ofrece Pilato.<\/p>\n<p>Entre las ambiciones que m\u00e1s ciegan el coraz\u00f3n de la persona est\u00e1 el poder. El poder que dispone de bienes y personas, la autoridad que debe ser obedecida, el ser tomado siempre en cuenta, es uno de esos virus que ataca y deforma a las personas. Hace que se olvide de los lazos de fraternidad y solidaridad con los hermanos y se asume como un privilegio para buscar los propios beneficios sin importar el pueblo. De hecho, sufrimos con frecuencia los mandatos desp\u00f3ticos de personas que antes se mostraban amables, interesadas y humanas. Se hace realidad aquella par\u00e1bola b\u00edblica (Jueces 9, 7s) cuando los \u00e1rboles quer\u00edan elegirse un rey; ninguno de ellos aceptaba para no perder su posibilidad de dar frutos y solamente lo acepta la zarza, pero al abrazarlos a todos con sus ramas, los pincha y los lastima. El poder se encarama sobre el pueblo que sufre y que padece hambre. Un pueblo que adem\u00e1s de todas las calamidades propias, tiene que ir cargando con una estructura autoritaria que, como par\u00e1sito, acaba chupando al que ya no aguanta m\u00e1s. La autoridad est\u00e1 para dar y proteger la vida, est\u00e1 para ayudar y buscar justicia. Entonces ser\u00e1 una verdadera autoridad.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuando Cristo afirma<em>: \u201cmi reino no es de este mundo\u201d, <\/em>algunos err\u00f3neamente han considerado como si estuviera diciendo que a \u00e9l no le interesa el bienestar de los necesitados y solamente se situara en el \u00e1mbito espiritual. Pero Jes\u00fas mismo contin\u00faa con su aclaraci\u00f3n: <em>\u201cSi mi Reino fuera de este mundo, mis servidores habr\u00edan luchado para que no cayera yo en manos de los jud\u00edos. Pero mi Reino no es de aqu\u00ed\u201d<\/em>.\u00a0 Es decir, no actuar\u00e1 al estilo de este mundo que se rige por la fuerza y la violencia. Para Juan, \u201cmundo\u201d con frecuencia no tiene el sentido de \u201cnaturaleza\u201d, sino designa las fuerzas del mal y del pecado. As\u00ed nos expresa que no ha venido a dominar ni infundir terror, sino a servir a la verdad y a la justicia. No se desconecta de todo compromiso con el orden temporal. Muy al contrario, Jes\u00fas se empe\u00f1a apasionadamente por la justicia y quiso cambiar el mundo.<\/p>\n<p>Jes\u00fas aparece como un rey justo. Justicia en la Biblia implica mucho m\u00e1s que derecho y misericordia: es el atributo fundamental de Dios. Justicia es comprometerse por los que no tienen protecci\u00f3n, es proteger y salvar su vida, es luchar contra todo desorden. Es intervenir de forma activa y tomar iniciativas a favor de la convivencia en la que todos vivan en paz. La justicia debe velar porque el derecho haga posible una existencia digna para todos los hombres. Jes\u00fas entreg\u00f3 su vida por la justicia y el letrero de la cruz declara la causa de su muerte: \u201cJes\u00fas Nazareno Rey de los jud\u00edos\u201d. Pero un rey que va m\u00e1s all\u00e1, hasta dar la vida por su pueblo. Jes\u00fas mismo afirma que es rey y que esa es su vocaci\u00f3n. Pero es el rey de la justicia y de la verdad, el rey de la paz y del amor.<\/p>\n<p>Hoy que sentimos que las estructuras nacionales y mundiales tiemblan y est\u00e1n a punto de caerse, convendr\u00eda que mir\u00e1ramos a Jes\u00fas y el reino que \u00e9l nos propone. \u00c9l nos da el verdadero sentido del reinado y del servicio. A Jes\u00fas se le enternec\u00eda el coraz\u00f3n frente a las ovejas descarriadas que sufr\u00edan el hambre y se compromet\u00eda en serio con ellas aunque fuera perseguido y criticado. Hoy sus verdaderos disc\u00edpulos no pueden hacerse desentendidos y pasar de lado ante tantas formas de opresi\u00f3n y sufrimiento. No debemos habituarnos a los pecados globales que son un reto y un desaf\u00edo: las cat\u00e1strofes del medio ambiente y el hambre, la pobreza, las guerras y la miseria de los migrantes, los ni\u00f1os que no tienen acceso a la salud y a la educaci\u00f3n, las mujeres maltratadas, las epidemias y tantas otras formas de dolor. El verdadero disc\u00edpulo, al igual que Jes\u00fas, dejar\u00e1 enternecer su coraz\u00f3n, se unir\u00e1 al que vive en el dolor y se comprometer\u00e1 en serio en la construcci\u00f3n de un \u201creino mejor\u201d. La oraci\u00f3n, la mirada atenta a las necesidades y el servicio fraternal, ser\u00e1n las se\u00f1ales de un disc\u00edpulo de este Rey que quiere construir su reinado de justicia y de paz. \u00bfQu\u00e9 estamos haciendo? \u00bfA qu\u00e9 nos compromete nuestro seguimiento de Cristo Rey?<\/p>\n<p><em>Dios todopoderoso y eterno, que quisiste fundar todas las cosas en tu Hijo muy amado, Rey del universo, haz que toda creatura, liberada de la esclavitud, sirva a tu majestad y te alabe eternamente. Am\u00e9n.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XXXIV Domingo Ordinario<\/p>\n","protected":false},"author":25,"featured_media":113482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[96,74],"tags":[33698,33703,27268,4895,33696,26182,5654,1372,33702,6308,676,33701,33700,414,14709,33697,33699,33704,4953,33695],"class_list":["post-113478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad","category-iglesia-y-mundo","tag-apocalipsis-15-8","tag-autoridad-verdadera","tag-compromiso-cristiano","tag-cristo-rey","tag-daniel-713-14","tag-discipulos-de-cristo","tag-enrique-diaz","tag-evangelio","tag-justicia-y-verdad","tag-mons-enrique-diaz","tag-oracion","tag-poder-y-justicia","tag-realeza-de-jesus","tag-reflexion","tag-reino-de-dios","tag-salmo-92","tag-san-juan-1833-37","tag-servicio-fraternal","tag-trending-es","tag-xxxiv-domingo-ordinario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"XXXIV Domingo Ordinario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-24T18:22:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-24T18:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enrique D\u00edaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrique D\u00edaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/\"},\"author\":{\"name\":\"Enrique D\u00edaz\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"headline\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey\",\"datePublished\":\"2024-11-24T18:22:19+00:00\",\"dateModified\":\"2024-11-24T18:23:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/\"},\"wordCount\":1111,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Cristo-scaled-1.jpg\",\"keywords\":[\"Apocalipsis 1:5-8\",\"autoridad verdadera\",\"compromiso cristiano\",\"Cristo Rey\",\"Daniel 7:13-14\",\"Disc\u00edpulos de Cristo\",\"Enrique D\u00edaz\",\"Evangelio\",\"justicia y verdad\",\"Mons. Enrique D\u00edaz\",\"Oraci\u00f3n\",\"poder y justicia\",\"realeza de Jes\u00fas\",\"Reflexi\u00f3n\",\"Reino de Dios\",\"Salmo 92\",\"San Juan 18:33-37\",\"servicio fraternal\",\"Trending\",\"XXXIV Domingo Ordinario\"],\"articleSection\":[\"Espiritualidad\",\"Iglesia y Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/\",\"name\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Cristo-scaled-1.jpg\",\"datePublished\":\"2024-11-24T18:22:19+00:00\",\"dateModified\":\"2024-11-24T18:23:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Cristo-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Cristo-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/reflexion-de-mons-enrique-diaz-cristo-rey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/c02ffbd10830fa375f6882f7dcf1844d\",\"name\":\"Enrique D\u00edaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g\",\"caption\":\"Enrique D\u00edaz\"},\"description\":\"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/enriquediaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/","og_locale":"es_ES","og_type":"article","og_title":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi","og_description":"XXXIV Domingo Ordinario","og_url":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2024-11-24T18:22:19+00:00","article_modified_time":"2024-11-24T18:23:55+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","type":"image\/jpeg"}],"author":"Enrique D\u00edaz","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Enrique D\u00edaz","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/"},"author":{"name":"Enrique D\u00edaz","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"headline":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey","datePublished":"2024-11-24T18:22:19+00:00","dateModified":"2024-11-24T18:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/"},"wordCount":1111,"image":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","keywords":["Apocalipsis 1:5-8","autoridad verdadera","compromiso cristiano","Cristo Rey","Daniel 7:13-14","Disc\u00edpulos de Cristo","Enrique D\u00edaz","Evangelio","justicia y verdad","Mons. Enrique D\u00edaz","Oraci\u00f3n","poder y justicia","realeza de Jes\u00fas","Reflexi\u00f3n","Reino de Dios","Salmo 92","San Juan 18:33-37","servicio fraternal","Trending","XXXIV Domingo Ordinario"],"articleSection":["Espiritualidad","Iglesia y Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/","url":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/","name":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","datePublished":"2024-11-24T18:22:19+00:00","dateModified":"2024-11-24T18:23:55+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/reflexion-de-mons-enrique-diaz-cristo-rey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Reflexi\u00f3n de Mons. Enrique D\u00edaz: Cristo Rey"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/c02ffbd10830fa375f6882f7dcf1844d","name":"Enrique D\u00edaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ca10be5325a95d04b74082d68ba605aa69611eb0f68f47096cb1bc349873284?s=96&d=mm&r=g","caption":"Enrique D\u00edaz"},"description":"Naci\u00f3 en Huandacareo, Michoac\u00e1n, M\u00e9xico, en 1952. Realiz\u00f3 sus estudios de Filosof\u00eda y Teolog\u00eda en el Seminario de Morelia. Ordenado di\u00e1cono el 22 de mayo de 1977, y presb\u00edtero el 23 de octubre del mismo a\u00f1o. Obtuvo la Licenciatura en Sagrada Escritura en el Pontificio Instituto B\u00edblico en Roma. Ha desarrollado m\u00faltiples encargos pastorales como el de capell\u00e1n de la rector\u00eda de las Tres Aves Mar\u00edas; responsable de la Pastoral B\u00edblica Diocesana y director de la Escuela B\u00edblica en Morelia; maestro de Biblia en el Seminario Conciliar de Morelia, p\u00e1rroco de la Parroquia de Nuestra Se\u00f1ora de Guadalupe, Col. Guadalupe, Morelia; o vicario episcopal para la Zona de Nuestra Se\u00f1ora de la Luz, P\u00e1tzcuaro. Ordenado obispo auxiliar de san Crist\u00f3bal de las Casas en 2003. En la Conferencia Episcopal form\u00f3 parte de las Comisiones de Biblia, Diaconado y Ministerios Laicales. Fue responsable de las Dimensiones de Ministerios Laicales, de Educaci\u00f3n y Cultura. Ha participado en encuentros latinoamericanos y mundiales sobre el Diaconado Permanente. Actualmente es el responsable de la Dimensi\u00f3n de Pastoral de la Cultura. Particip\u00f3 como Miembro del S\u00ednodo de Obispos sobre la Palabra de Dios en la Vida y Misi\u00f3n de la Iglesia en Roma, en 2008. Recibi\u00f3 el nombramiento de obispo coadjutor de San Crist\u00f3bal de las Casas en 2014. Nombrado II obispo de Irapuato el d\u00eda 11 de marzo, tom\u00f3 posesi\u00f3n el 19 de Mayo. Colabora en varias revistas y publicaciones sobre todo con la reflexi\u00f3n diaria y dominical tanto en audio como escrita.","url":"https:\/\/exaudi.org\/es\/author\/enriquediaz\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/Cristo-scaled-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-twi","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/113478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=113478"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/113478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/113482"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=113478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=113478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=113478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}