{"id":112419,"date":"2024-11-28T08:30:15","date_gmt":"2024-11-28T07:30:15","guid":{"rendered":"https:\/\/exaudi.org\/?p=112419"},"modified":"2024-11-28T12:08:09","modified_gmt":"2024-11-28T11:08:09","slug":"para-dar-gracias-siempre","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/","title":{"rendered":"\u00a1Para dar gracias siempre!"},"content":{"rendered":"<p>Anualmente, el cuarto jueves del mes de noviembre, en los Estados Unidos de Norteam\u00e9rica celebramos el llamado \u201cD\u00cdA DE ACCI\u00d3N DE GRACIAS\u201d.<\/p>\n<p><iframe title=\"Spotify Embed: \u00a1Para dar gracias siempre!\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/3a5LfkaR8eOWx07S6wZ4eh?si=ee8263b1a0d94e94&#038;utm_source=oembed\"><\/iframe><\/p>\n<p>Los or\u00edgenes de esta celebraci\u00f3n nacional se remontan e inspiran en un encuentro ocurrido en el a\u00f1o 1621, cuando colonos ingleses de Plymouth &#8211; los llamados \u201cperegrinos\u201d &#8211; y el pueblo aborigen Wampanoag compartieron \u2013 en fraternidad y paz &#8211; los frutos de su caza y su cosecha. Despu\u00e9s, entre muchos vaivenes en la historia de esta naci\u00f3n, esta celebraci\u00f3n se ha mantenido como la fiesta nacional por excelencia. Fecha en la que todos los estadounidenses se encuentran, se re\u00fanen en familia, se regalan, brindan y comparten una cena familiar.<\/p>\n<p>Junto a Canad\u00e1 (aunque en diferente fecha) y unos pocos pa\u00edses m\u00e1s, es Estados Unidos la naci\u00f3n que celebra este D\u00cdA DE ACCI\u00d3N DE GRACIAS. Es admirable que la fecha patria nacional que m\u00e1s nos congrega y nos identifica como pa\u00eds tenga como pretexto y contexto un encuentro familiar para DAR GRACIAS. Porque la acci\u00f3n de gracias, la gratitud, que es una actitud profunda y esencialmente humana, casi siempre ligada a la esfera de lo religioso, entre nosotros se convierte, cada a\u00f1o, en una celebraci\u00f3n que a todos nos alegra, nos convoca, nos congrega y nos interpela.<\/p>\n<p>Y es que la gratitud a Dios, a la vida o a los otros, es \u2013 en primer lugar &#8211; una virtud y una actitud que nace en el ser humano por el reconocimiento de lo positivo que hay en su existencia, en su historia, y que \u2013 en segundo lugar \u2013 empuja a corresponder al benefactor, con bondad y bien, de alguna manera.<\/p>\n<p>As\u00ed, la gratitud se convierte en una actitud, en un estilo de vida, de quienes son capaces de reconocer y recibir como don, como regalo, la vida y, al mismo tiempo, de dar y compartir ese don recibido y agradecido con los dem\u00e1s, especialmente con los m\u00e1s vulnerables y necesitados de la sociedad. Porque, como dice la canci\u00f3n, \u201c<em>amor con amor se paga<\/em>\u201d.<\/p>\n<p>Entonces, el D\u00cdA DE ACCI\u00d3N DE GRACIAS nos exige a todos, por una parte, abrir los sentidos para ser capaces de tomar conciencia, de reconocer, todo lo bueno que hay en nuestras historias personales, familiares y colectivas y para ser capaces \u2013 solidaria y colectivamente &#8211; de agradecer por todo lo logrado, por todos los bienes y bendiciones alcanzadas a lo largo del a\u00f1o.<\/p>\n<p>Pero, por otra parte, el D\u00cdA DE ACCI\u00d3N DE GRACIAS nos exige ser capaces de compartir, de <em>\u201cdar gratis lo que hemos recibido gratis<\/em>\u201d, de crear condiciones familiares y sociales de vida abundante, de prosperidad, de bien, de bondad y de bendiciones para todos, de tal manera que todos \u2013 como naci\u00f3n \u2013 encontremos y tengamos motivos para agradecer, para DAR GRACIAS.<\/p>\n<p>Son muchos los factores que hoy atentan contra esta celebraci\u00f3n de ACCI\u00d3N DE GRACIAS. En primer lugar, la rutina celebrativa anual que puede vaciar de contenido, de sentido y de significado la celebraci\u00f3n. Es decir, que podemos reunirnos y celebrar sin saber por qu\u00e9 nos reunimos ni qu\u00e9 es lo que celebramos anualmente.<\/p>\n<p>Un segundo enemigo contra la celebraci\u00f3n de ACCI\u00d3N DE GRACIAS lo constituye nuestra coyuntura socio-cultural, es decir, la transici\u00f3n de la modernidad a la postmodernidad, que &#8211; como caracter\u00edstica principal de este momento &#8211; impide al hombre descubrir la gratuidad de y en la vida, por una p\u00e9rdida de la visi\u00f3n trascendente de la existencia humana.<\/p>\n<p>Porque, apegados al dinero, al tener y embrutecidos en el frenes\u00ed del consumismo y del intercambio material y comercial, en una sociedad y mundo donde todo tiene un precio, nos volvemos miopes para descubrir todo lo mejor, todo lo bueno, lo bello, lo noble y gratis que tiene la vida. Todo lo mejor y m\u00e1s valioso de la vida humana, que no se compra y no se vende.<\/p>\n<p>En tercer lugar, el olvido o la indiferencia ante la suma de todos los males que a nivel nacional y mundial padecemos pueden convertir en c\u00ednica nuestra celebraci\u00f3n de acci\u00f3n de gracias. Porque los conflictos b\u00e9licos, los desgobiernos, la inequidad y la injusticia social, la violencia, tantas formas de corrupci\u00f3n y de muerte no son razones para agradecer y celebrar con verdad y con sentido esta fecha.<\/p>\n<p>Cabe entonces que nos preguntemos \u00bfPor qu\u00e9 agradecemos? \u00bfQu\u00e9 motivos tenemos para agradecer? \u00bfC\u00f3mo superar el mal personal y social para crear espacios y razones para la gratitud? \u00bfC\u00f3mo trabajar juntos para construir motivos para dar gracias?<\/p>\n<p>La gratitud entonces no se circunscribe a una fecha, a una celebraci\u00f3n anual. La gratitud es una actitud, un estilo de vida de quienes son capaces de descubrir motivos para agradecer y, por ello, capaces de ser felices.<\/p>\n<p>La gratitud es la actitud y vida de quienes construyen motivos para seguir creyendo en un mundo distinto y mejor, en un mundo nuevo, m\u00e1s justo y m\u00e1s humano. La gratitud es un estilo de vida de todos los hombres y mujeres que construyen esperanza.<\/p>\n<p>Nos congratulamos todos en esta hermosa celebraci\u00f3n nacional y, ojal\u00e1, que animados por el nuevo gobierno nacional reci\u00e9n electo y pr\u00f3ximo a inaugurarse, nos comprometamos todos con la construcci\u00f3n de una naci\u00f3n y un mundo llenos de motivos para agradecer, para dar gracias todos los d\u00edas.<\/p>\n<p>\u00a1<em>Feliz d\u00eda de acci\u00f3n de gracias!<\/em><\/p>\n<p><strong><em>Mario J. Paredes es director ejecutivo de SOMOS Community Care, una red de atenci\u00f3n social de m\u00e1s de 2500 proveedores independientes responsables de llegar y brindar<\/em> <em>atenci\u00f3n a m\u00e1s de 1 mill\u00f3n de pacientes de Medicaid en toda la ciudad de Nueva York<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una celebraci\u00f3n de gratitud y uni\u00f3n familiar<\/p>\n","protected":false},"author":114,"featured_media":112421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[130],"tags":[30956,913,30958,18838,30960,21371,3158,30955,624,565,19148,617,2419,8003,1767,7881,9515,9214,14268,30959,726,7882,9437,1313,725,10052,30957],"class_list":["post-112419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-accion-de-gracias","tag-bendiciones","tag-celebracion-nacional","tag-compartir","tag-conflicto-belico","tag-consumismo-2","tag-corrupcion","tag-dia-de-accion-de-gracias","tag-esperanza","tag-estados-unidos","tag-existencia-humana","tag-familia","tag-featured","tag-gratitud","tag-justicia-social","tag-mario-j-paredes","tag-modernidad","tag-peregrinos","tag-postmodernidad","tag-prosperidad","tag-solidaridad","tag-somos-community-care","tag-tradicion","tag-vida","tag-violencia","tag-virtud","tag-wampanoag"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Para dar gracias siempre! &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Para dar gracias siempre! &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Una celebraci\u00f3n de gratitud y uni\u00f3n familiar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/SOMOSCommunityCare\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T07:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T11:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario J. Paredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SOMOSCare\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario J. Paredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/\"},\"author\":{\"name\":\"Mario J. Paredes\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\"},\"headline\":\"\u00a1Para dar gracias siempre!\",\"datePublished\":\"2024-11-28T07:30:15+00:00\",\"dateModified\":\"2024-11-28T11:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/\"},\"wordCount\":994,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1\",\"keywords\":[\"acci\u00f3n de gracias\",\"bendiciones\",\"celebraci\u00f3n nacional\",\"compartir\",\"conflicto b\u00e9lico\",\"consumismo\",\"Corrupci\u00f3n\",\"D\u00eda de Acci\u00f3n de Gracias\",\"Esperanza\",\"Estados Unidos\",\"existencia humana\",\"Familia\",\"Featured\",\"Gratitud\",\"Justicia Social\",\"Mario J Paredes\",\"Modernidad\",\"Peregrinos\",\"postmodernidad\",\"prosperidad\",\"solidaridad\",\"SOMOS Community Care\",\"Tradici\u00f3n\",\"Vida\",\"violencia\",\"Virtud\",\"Wampanoag\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/\",\"name\":\"\u00a1Para dar gracias siempre! &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2024-11-28T07:30:15+00:00\",\"dateModified\":\"2024-11-28T11:08:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707,\"caption\":\"Pexels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/para-dar-gracias-siempre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Para dar gracias siempre!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f4babf785ff6e9ecd6850d1802095c1d\",\"name\":\"Mario J. Paredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g\",\"caption\":\"Mario J. Paredes\"},\"description\":\"Presidente ejecutivo de SOMOS Community Care, una red de 2,600 m\u00e9dicos independientes -en su mayor\u00eda de atenci\u00f3n primaria- que atienden a cerca de un mill\u00f3n de los pacientes m\u00e1s vulnerables del Medicaid de la Ciudad de Nueva York\",\"sameAs\":[\"http:\\\/\\\/somosnyhealth.org\",\"https:\\\/\\\/www.facebook.com\\\/SOMOSCommunityCare\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somoscare\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/somoscommunitycare\\\/\",\"https:\\\/\\\/x.com\\\/SOMOSCare\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUrnRjEHj5UrNvxU0jHSzQQ\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/mario-j-paredes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Para dar gracias siempre! &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Para dar gracias siempre! &#8211; Exaudi","og_description":"Una celebraci\u00f3n de gratitud y uni\u00f3n familiar","og_url":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/SOMOSCommunityCare\/","article_published_time":"2024-11-28T07:30:15+00:00","article_modified_time":"2024-11-28T11:08:09+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg","type":"image\/jpeg"}],"author":"Mario J. Paredes","twitter_card":"summary_large_image","twitter_creator":"@SOMOSCare","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Mario J. Paredes","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/"},"author":{"name":"Mario J. Paredes","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d"},"headline":"\u00a1Para dar gracias siempre!","datePublished":"2024-11-28T07:30:15+00:00","dateModified":"2024-11-28T11:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/"},"wordCount":994,"image":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1","keywords":["acci\u00f3n de gracias","bendiciones","celebraci\u00f3n nacional","compartir","conflicto b\u00e9lico","consumismo","Corrupci\u00f3n","D\u00eda de Acci\u00f3n de Gracias","Esperanza","Estados Unidos","existencia humana","Familia","Featured","Gratitud","Justicia Social","Mario J Paredes","Modernidad","Peregrinos","postmodernidad","prosperidad","solidaridad","SOMOS Community Care","Tradici\u00f3n","Vida","violencia","Virtud","Wampanoag"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/","url":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/","name":"\u00a1Para dar gracias siempre! &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1","datePublished":"2024-11-28T07:30:15+00:00","dateModified":"2024-11-28T11:08:09+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#primaryimage","url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1","width":2560,"height":1707,"caption":"Pexels"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/para-dar-gracias-siempre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Para dar gracias siempre!"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f4babf785ff6e9ecd6850d1802095c1d","name":"Mario J. Paredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28c707f8b881139d324797c87373ccf8502494a7f73d0f6d23dcda1548e9d254?s=96&d=mm&r=g","caption":"Mario J. Paredes"},"description":"Presidente ejecutivo de SOMOS Community Care, una red de 2,600 m\u00e9dicos independientes -en su mayor\u00eda de atenci\u00f3n primaria- que atienden a cerca de un mill\u00f3n de los pacientes m\u00e1s vulnerables del Medicaid de la Ciudad de Nueva York","sameAs":["http:\/\/somosnyhealth.org","https:\/\/www.facebook.com\/SOMOSCommunityCare\/","https:\/\/www.instagram.com\/somoscare\/","https:\/\/www.linkedin.com\/company\/somoscommunitycare\/","https:\/\/x.com\/SOMOSCare","https:\/\/www.youtube.com\/channel\/UCUrnRjEHj5UrNvxU0jHSzQQ"],"url":"https:\/\/exaudi.org\/es\/author\/mario-j-paredes\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/exaudi.org\/wp-content\/uploads\/2024\/11\/pexels-cottonbro-5791675-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-tfd","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/112419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=112419"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/112419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/112421"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=112419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=112419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=112419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}