{"id":107264,"date":"2024-09-03T09:00:46","date_gmt":"2024-09-03T07:00:46","guid":{"rendered":"https:\/\/exaudi.org\/?p=107264"},"modified":"2024-09-03T09:53:16","modified_gmt":"2024-09-03T07:53:16","slug":"la-vida-familiar-del-directivo-de-empresa","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/","title":{"rendered":"La vida familiar del directivo de empresa"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-107264-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/La-vida-familiar-del-directivo-de-empresa.mp3?_=1\" \/><a href=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/La-vida-familiar-del-directivo-de-empresa.mp3\">https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/La-vida-familiar-del-directivo-de-empresa.mp3<\/a><\/audio>\n<p>La familia ocupa un lugar excepcional en la vida de cualquier ser humano, y por tanto del directivo. Sin embargo, las exigencias de los resultados del entorno empresarial con frecuencia llevan a olvidar esta realidad.<\/p>\n<p>La dedicaci\u00f3n al trabajo no amerita un descuido de la vida familiar, porque \u201cen la familia se realizan bienes humanos excelentes\u201d, y adem\u00e1s: \u201clos bienes de la familia y el hogar son la parte m\u00e1s importante de la felicidad humana\u201d (Lorda, 2010). Las actividades del hogar nos parecen -y realmente lo son-, actividades muy vulgares; y que, por tanto, no pasa nada si no las hacemos. Acompa\u00f1ar a un hijo de ocho a\u00f1os en su partido de f\u00fatbol; explicar una lecci\u00f3n de matem\u00e1tica; llegar a tiempo para acostar al m\u00e1s peque\u00f1o; ordenar una habitaci\u00f3n: todo esto nos parece tan vulgar, que lo imaginamos como delegable o que al dejarlo de hacer no ocurre nada grave.<\/p>\n<p>Y efectivamente, todo eso es muy vulgar, y m\u00e1s a\u00fan, nos parece que cualquiera podr\u00eda hacerlo; pero todo eso es -al mismo tiempo- muy noble, muy humano y muy aut\u00e9ntico. Y por tanto, cuando lo hace un directivo de empresa, ocurre algo maravilloso: \u00e9l se hace m\u00e1s noble, m\u00e1s humano y m\u00e1s aut\u00e9ntico.<\/p>\n<p>De otro lado, como la sobrevivencia de la empresa requiere resultados, el entorno empresarial se vuelve \u201cexcesivamente\u201d objetivo en la evaluaci\u00f3n de los miembros de la empresa. Y cada uno cuenta por lo que aporta a la organizaci\u00f3n: por eso, no se ve bien que alguien est\u00e9 en la organizaci\u00f3n y no aporte lo que los dem\u00e1s; y que lo sostenga el esfuerzo de los dem\u00e1s.<\/p>\n<p>Por eso, no es extra\u00f1o que este modo de pensar se traslade -casi involuntariamente- al \u00e1mbito familiar, donde la l\u00f3gica es bastante distinta. \u00a0En palabras de Benedicto XVI:<\/p>\n<p class=\"has-text-align-center\" style=\"text-align: center\"><strong>la familia natural, en cuanto comuni\u00f3n \u00edntima de vida y amor, fundada en el matrimonio entre un hombre y una mujer, es el lugar primario de \u2018humanizaci\u00f3n\u2019 de la persona y de la sociedad, la \u2018cuna de la vida y del amor\u2019 (2007).<\/strong><\/p>\n<p>En la vida familiar, a las personas no se les acepta por su aporte, sino por lo que son: hijos, padres, abuelos o t\u00edos. Nadie debe demostrar que es valioso para que se le quiera y se le atienda. Y es que, como comenta Lorda, \u201clos lazos de la carne y de la sangre son los cauces naturales y espont\u00e1neos del amor, de la confianza e incluso de la econom\u00eda\u201d (2010).<\/p>\n<p>Por eso, lo primero que deber\u00eda advertir un buen profesional al regresar a casa es el cambio de l\u00f3gica, porque de no hacerlo calificar\u00e1 mal muchas de las realidades que se le presentar\u00e1n en ese ambiente. El hogar es el lugar donde cada uno se manifiesta como es; y esto da al ambiente una sensaci\u00f3n de paz y confianza muy grande. All\u00ed es donde se experimenta \u201cel servicio afectuoso a los miembros m\u00e1s d\u00e9biles, porque son peque\u00f1os, ancianos o est\u00e1n enfermos, la ayuda mutua en las necesidades de la vida, la disponibilidad para acoger al otro y, si fuera necesario, para perdonarlo\u201d (Benedicto XVI, 2008).<\/p>\n<p>Para terminar esta breve reflexi\u00f3n, tomar\u00eda una cita de Juan Luis Lorda, que refleja muy bien el gran impacto que tiene la vida familiar en el \u00e1mbito laboral y en la sociedad:<\/p>\n<p class=\"has-text-align-center\" style=\"text-align: center\"><strong>si los padres son sanos y tienen un m\u00ednimo de dominio de s\u00ed mismos, llegar\u00e1n a querer mucho a sus hijos; y ese amor los llevar\u00e1 a ser m\u00e1s responsables, mejores trabajadores, mejores ciudadanos, mejores hombres; les dar\u00e1 una tarea y unas aspiraciones: har\u00e1 que su vida tenga sentido, y les proporcionar\u00e1 muchos momentos de orgullo y felicidad\u201d (2010).<\/strong><\/p>\n<p>Y esto dejar\u00e1 un legado. La siguiente generaci\u00f3n habr\u00e1 aprendido en la escuela del hogar la realidad m\u00e1s profunda de la vida humana: que la vida familiar es una componente esencial de la felicidad personal. En palabras de Benedicto XVI: \u00absolo as\u00ed ser\u00e1 posible ayudar a los j\u00f3venes a comprender los valores de la vida, del amor, del matrimonio y de la familia. Solo as\u00ed se podr\u00e1 hacer que aprecien la belleza y la santidad del amor, la alegr\u00eda y la responsabilidad de ser padres y colaboradores de Dios para dar la vida\u00bb (2007).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-107408 alignnone\" src=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1.jpg\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1.jpg 940w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1-300x251.jpg 300w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1-770x645.jpg 770w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1-500x419.jpg 500w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1-293x246.jpg 293w, https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/Copia-de-voces-1-390x327.jpg 390w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si los padres son sanos y tienen un m\u00ednimo de dominio de s\u00ed mismos, llegar\u00e1n a querer mucho a sus hijos<\/p>\n","protected":false},"author":57,"featured_media":107265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[130],"tags":[2596,19948,515,22985,22143,22988,22987,22990,22993,22989,22992,2618,22986,18427,22991,4953,19018,11148],"class_list":["post-107264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voces","tag-alejandro-fontana","tag-amor-familiar","tag-benedicto-xvi","tag-directivo-de-empresa","tag-educacion-en-el-hogar","tag-equilibrio-trabajo-familia","tag-familia-y-trabajo","tag-felicidad-personal","tag-humanizacion","tag-juan-luis-lorda","tag-liderazgo-empresarial","tag-matrimonio-es","tag-padres-e-hijos","tag-relaciones-familiares","tag-responsabilidad-parental","tag-trending-es","tag-valores-familiares","tag-vida-familiar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vida familiar del directivo de empresa &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vida familiar del directivo de empresa &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Si los padres son sanos y tienen un m\u00ednimo de dominio de s\u00ed mismos, llegar\u00e1n a querer mucho a sus hijos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T07:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T07:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro Fontana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro Fontana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/\"},\"author\":{\"name\":\"Alejandro Fontana\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\"},\"headline\":\"La vida familiar del directivo de empresa\",\"datePublished\":\"2024-09-03T07:00:46+00:00\",\"dateModified\":\"2024-09-03T07:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/\"},\"wordCount\":760,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pexels-vinh-ch-1599393606-27647255-scaled.jpg\",\"keywords\":[\"Alejandro Fontana\",\"amor familiar\",\"Benedicto XVI\",\"directivo de empresa\",\"Educaci\u00f3n en el Hogar\",\"equilibrio trabajo-familia\",\"familia y trabajo\",\"felicidad personal\",\"humanizaci\u00f3n\",\"Juan Luis Lorda\",\"liderazgo empresarial\",\"matrimonio\",\"padres e hijos\",\"relaciones familiares\",\"responsabilidad parental\",\"Trending\",\"valores familiares\",\"Vida familiar\"],\"articleSection\":[\"Voces\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/\",\"name\":\"La vida familiar del directivo de empresa &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pexels-vinh-ch-1599393606-27647255-scaled.jpg\",\"datePublished\":\"2024-09-03T07:00:46+00:00\",\"dateModified\":\"2024-09-03T07:53:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pexels-vinh-ch-1599393606-27647255-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pexels-vinh-ch-1599393606-27647255-scaled.jpg\",\"width\":2560,\"height\":1564,\"caption\":\"Pexels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-vida-familiar-del-directivo-de-empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vida familiar del directivo de empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/036aa1cfc8cb49829af5d777f3965ad7\",\"name\":\"Alejandro Fontana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g\",\"caption\":\"Alejandro Fontana\"},\"description\":\"Profesor de Direcci\u00f3n General y Control Directivo. Consultor en Direcci\u00f3n General para empresas y organizaciones c\u00edvicas. Doctorado en Planificaci\u00f3n y Desarrollo; M\u00e1ster en Organizaciones y Comportamiento Humano; M.B.A. y M.E. en Ingenier\u00eda Civil. Miembro del grupo de investigaci\u00f3n GESPLAN de la Universidad Polit\u00e9cnica de Madrid. \u00c1reas de inter\u00e9s: cooperaci\u00f3n horizontal; relaci\u00f3n empresa-sociedad civil; negocios internacionales y an\u00e1lisis de estrategias empresariales.\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/alejandrofontana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vida familiar del directivo de empresa &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/","og_locale":"es_ES","og_type":"article","og_title":"La vida familiar del directivo de empresa &#8211; Exaudi","og_description":"Si los padres son sanos y tienen un m\u00ednimo de dominio de s\u00ed mismos, llegar\u00e1n a querer mucho a sus hijos","og_url":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_published_time":"2024-09-03T07:00:46+00:00","article_modified_time":"2024-09-03T07:53:16+00:00","og_image":[{"width":2560,"height":1564,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","type":"image\/jpeg"}],"author":"Alejandro Fontana","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_News","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Alejandro Fontana","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/"},"author":{"name":"Alejandro Fontana","@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7"},"headline":"La vida familiar del directivo de empresa","datePublished":"2024-09-03T07:00:46+00:00","dateModified":"2024-09-03T07:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/"},"wordCount":760,"image":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","keywords":["Alejandro Fontana","amor familiar","Benedicto XVI","directivo de empresa","Educaci\u00f3n en el Hogar","equilibrio trabajo-familia","familia y trabajo","felicidad personal","humanizaci\u00f3n","Juan Luis Lorda","liderazgo empresarial","matrimonio","padres e hijos","relaciones familiares","responsabilidad parental","Trending","valores familiares","Vida familiar"],"articleSection":["Voces"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/","url":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/","name":"La vida familiar del directivo de empresa &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","datePublished":"2024-09-03T07:00:46+00:00","dateModified":"2024-09-03T07:53:16+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","width":2560,"height":1564,"caption":"Pexels"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/la-vida-familiar-del-directivo-de-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La vida familiar del directivo de empresa"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/036aa1cfc8cb49829af5d777f3965ad7","name":"Alejandro Fontana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/288eb00d08e23df21f6e88a59ea2dd3df4566ed7b431ac0bcf3fbf94354fa324?s=96&d=mm&r=g","caption":"Alejandro Fontana"},"description":"Profesor de Direcci\u00f3n General y Control Directivo. Consultor en Direcci\u00f3n General para empresas y organizaciones c\u00edvicas. Doctorado en Planificaci\u00f3n y Desarrollo; M\u00e1ster en Organizaciones y Comportamiento Humano; M.B.A. y M.E. en Ingenier\u00eda Civil. Miembro del grupo de investigaci\u00f3n GESPLAN de la Universidad Polit\u00e9cnica de Madrid. \u00c1reas de inter\u00e9s: cooperaci\u00f3n horizontal; relaci\u00f3n empresa-sociedad civil; negocios internacionales y an\u00e1lisis de estrategias empresariales.","url":"https:\/\/exaudi.org\/es\/author\/alejandrofontana\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/09\/pexels-vinh-ch-1599393606-27647255-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-rU4","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/107264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=107264"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/107264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/107265"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=107264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=107264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=107264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}