{"id":105994,"date":"2024-10-02T14:13:17","date_gmt":"2024-10-02T12:13:17","guid":{"rendered":"https:\/\/exaudi.org\/?p=105994"},"modified":"2026-01-14T12:56:37","modified_gmt":"2026-01-14T11:56:37","slug":"oracion-de-abandono","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/","title":{"rendered":"Oraci\u00f3n del abandono"},"content":{"rendered":"<p>El Padre Dolindo Ruotolo fue un sacerdote napolitano (1882-1970), m\u00edstico y \u201cportavoz del Esp\u00edritu Santo\u201d. A lo largo de su vida heroica, tuvo una extraordinaria comunicaci\u00f3n con Jes\u00fas, dedic\u00e1ndose por completo a Dios y a la Santa Madre Mar\u00eda. Se refer\u00eda a s\u00ed mismo como \u201cel viejito de Nuestra Se\u00f1ora\u201d y encontraba en el Rosario su compa\u00f1ero constante.<\/p>\n<p><iframe title=\"Spotify Embed: Oraci\u00f3n del abandono\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/4KfC3pe0ExCUIemASZSGtW?si=29e544491dd643bf&amp;utm_source=oembed\"><\/iframe><\/p>\n<p>En su oraci\u00f3n, vemos c\u00f3mo lo que nuestro Se\u00f1or desea para nosotros trasciende la inclinaci\u00f3n humana y la raz\u00f3n. Solo podemos alcanzar este nivel de entendimiento a trav\u00e9s de la gracia de Dios y la ayuda del Esp\u00edritu Santo.<\/p>\n<p>Debemos dejar de lado nuestros problemas, dejar de preocuparnos y tratar de resolverlos por nosotros mismos. Debemos creer, confiar y permitir que nuestro Se\u00f1or nos rescate de nosotros mismos y atienda nuestros deseos y necesidades, resolviendo nuestros problemas conforme a Su Divina Voluntad.<\/p>\n<p>\u00abJes\u00fas, oc\u00fapate T\u00fa de ello\u00bb deben ser siempre las primeras palabras que vengan a nuestra mente y fluyan de nuestros labios. Despu\u00e9s de todo, hemos intentado muchas cosas a nuestra manera, y ya hemos visto a d\u00f3nde nos ha llevado esto.<\/p>\n<p>Sigamos lo que dice la oraci\u00f3n, abramos nuestros corazones y mentes en amor, cerremos nuestros ojos en confianza y pid\u00e1mosle a Jes\u00fas que se encargue de todo. \u00a1\u00c9l lo har\u00e1!<\/p>\n<p>La oraci\u00f3n del Abandono procede del Padre Dolindo Ruotolo, Siervo de Dios y candidato a la beatificaci\u00f3n. Jes\u00fas revel\u00f3 al Padre Dolindo las palabras que componen esta oraci\u00f3n. Padre Dolindo, conocido como \u00abel viejecito de Mar\u00eda\u00bb, sufri\u00f3 gran parte de su vida, llegando incluso a vivir paralizado los \u00faltimos diez a\u00f1os antes de su muerte. Tambi\u00e9n fue, en un tiempo, director espiritual y amigo del Padre P\u00edo, quien, del mismo modo, encontr\u00f3 el amor de Cristo en su sufrimiento.<\/p>\n<p>Tanto el Padre Dolindo como el Padre P\u00edo nos dejaron muchas palabras y oraciones que nos gu\u00edan hacia la entrega a Cristo. Nos inspiran a siempre encontrar a los dem\u00e1s con misericordia y amor, reflejando sus propias entregas a Cristo y su amor por nosotros.<\/p>\n<p>Al rezar esta oraci\u00f3n de entrega, meditamos sobre las mismas palabras que Jes\u00fas dio al Padre Dolindo. En esta oraci\u00f3n, escuchamos a Jes\u00fas decirnos que le demos todo y pongamos en \u00c9l toda nuestra confianza.<\/p>\n<h3><strong>Oraci\u00f3n del abandono<\/strong><\/h3>\n<p>\u00bfPor qu\u00e9 os confund\u00eds, angusti\u00e1ndoos? Dejad a m\u00ed la gesti\u00f3n de vuestros asuntos y todo se calmar\u00e1. En verdad os digo que cada acto de verdadero, ciego y completo abandono en m\u00ed, produce el efecto que dese\u00e1is y resuelve los problemas m\u00e1s espinosos.<\/p>\n<p>Abandonarse en m\u00ed no significa atormentarse, alterarse o desesperarse, dirigi\u00e9ndome luego una oraci\u00f3n llena de inquietud para que yo os siga a vosotros y cambie as\u00ed la inquietud en la oraci\u00f3n. Abandonarse significa cerrar pl\u00e1cidamente los ojos del alma, apartar el pensamiento de la tribulaci\u00f3n y confiarse a m\u00ed para que s\u00f3lo yo obre, dici\u00e9ndome: \u201c<b><i>oc\u00fapate T\u00fa\u201d<\/i><\/b>. La preocupaci\u00f3n, la turbaci\u00f3n, el querer pensar en las consecuencias de un hecho son cosas contrarias al abandono, contrarias por naturaleza.<\/p>\n<p>Es como la confusi\u00f3n que traen los ni\u00f1os que pretenden que la mam\u00e1 piense en sus necesidades, pero quieren tambi\u00e9n resolverlas por s\u00ed solos y as\u00ed obstaculizan, con sus ideas y sus fijaciones infantiles, su trabajo.<\/p>\n<p>Cerrad los ojos y dejaos llevar por la corriente de mi gracia; cerrad los ojos y no pensad m\u00e1s que en el momento presente, alej\u00e1ndoos del pensamiento del futuro como de una tentaci\u00f3n; reposad en mi creyendo en mi bondad, y os juro por mi amor que, dici\u00e9ndome con estas disposiciones: \u201c<b><i>oc\u00fapate T\u00fa\u201d<\/i><\/b>, yo lo har\u00e9 por entero, os consolar\u00e9, os librar\u00e9, os guiar\u00e9.<\/p>\n<p>Y cuando tenga que llevaros por un camino diferente de aquel que veis vosotros, yo os adiestrar\u00e9, os llevar\u00e9 en mis brazos, har\u00e9 que os encontr\u00e9is en la otra orilla, como ni\u00f1os dormidos en los brazos maternos. Lo que os turba y os hace un da\u00f1o inmenso son vuestros razonamientos, vuestras preocupaciones, vuestros afanes, y el querer a toda costa ser vosotros quienes remedi\u00e9is aquello que os aflige.<\/p>\n<p>\u00a1Cu\u00e1ntas cosas realizo cuando el alma, tanto en sus necesidades espirituales como en aquellas materiales, se vuelve a m\u00ed, me mira y dici\u00e9ndome:\u00a0<b><i>\u201coc\u00fapate T\u00fa\u201d<\/i><\/b>, cierra los ojos y reposa. Obten\u00e9is pocas gracias cuando os atorment\u00e1is por producirlas, sin embargo ten\u00e9is much\u00edsimas cuando la oraci\u00f3n es un encomendarse plenamente a m\u00ed. En el dolor, vosotros or\u00e1is para que yo obre, pero para que obre como cre\u00e9is que debo obrar\u2026 No os dirig\u00eds a m\u00ed, sino que quer\u00e9is que yo me adapte a vuestras ideas; no sois enfermos que piden al m\u00e9dico que les cure, sino que le suger\u00eds la cura. No obr\u00e9is as\u00ed, sino orad como os he ense\u00f1ado en el Padrenuestro:<\/p>\n<p><i>Santificado sea tu nombre<\/i>, es decir, sed glorificado en esta necesidad m\u00eda.<br \/>\n<i>Venga a nosotros tu reino<\/i>, o sea, todo contribuya a tu reinado en nosotros y en el mundo.<br \/>\n<i>H\u00e1gase tu voluntad as\u00ed en la tierra, como en el cielo<\/i>, es decir, disp\u00f3n T\u00fa, en esta necesidad, como mejor te parezca en lo tocante a nuestra vida temporal y eterna.<\/p>\n<p>Si me dec\u00eds de verdad: \u201c<i>h\u00e1gase tu voluntad\u201d<\/i>, que es lo mismo que decir: \u201c<b><i>oc\u00fapate T\u00fa\u201d<\/i><\/b>, yo intervendr\u00e9 con toda mi omnipotencia y vencer\u00e9 las mayores dificultades. Mira, \u00bft\u00fa ves que la enfermedad apremia en vez de menguar? No te turbes, cierra los ojos y dime con confianza:\u00a0<i>h\u00e1gase tu voluntad<\/i>,\u00a0<b><i>\u201coc\u00fapate T\u00fa\u201d<\/i><\/b>.<\/p>\n<p>Te digo que as\u00ed lo har\u00e9 y que intervendr\u00e9 como m\u00e9dico, y que hasta obrar\u00e9 un milagro cuando fuere menester. \u00bfVes que el enfermo empeora? No te desanimes, sino cierra los ojos y di:\u00a0<b>\u201coc\u00fapate T\u00fa\u201d<\/b>. Te digo que yo me ocupar\u00e9, y que no hay medicina m\u00e1s poderosa que una intervenci\u00f3n m\u00eda de amor. Me ocupar\u00e9 de ello s\u00f3lo cuando\u00a0<i>cerr\u00e9is los ojos<\/i>.<\/p>\n<p>No descans\u00e1is nunca, quer\u00e9is valorarlo todo, escudri\u00f1arlo todo, pensar en todo, y os abandon\u00e1is as\u00ed a las fuerzas humanas, o peor, a los hombres, confiando en su intervenci\u00f3n. Es esto lo que obstaculiza, impide mis palabras y mis c\u00e1lculos. \u00a1Oh, como deseo vuestro abandono para beneficiaros!, \u00a1Y cuanto me aflijo al veros turbados! Satan\u00e1s tiende precisamente a esto:\u00a0<i>a turbaros<\/i>\u00a0para apartaros de mi acci\u00f3n y arrojaros a la merced de las iniciativas humanas.<\/p>\n<p>Confiad por eso s\u00f3lo en m\u00ed, reposad en m\u00ed, abandonaos a m\u00ed en todo. Yo obro milagros en proporci\u00f3n del pleno abandono en m\u00ed, y a la ausencia de preocupaciones vuestras. \u00a1Yo derramo tesoros de gracia cuando vosotros est\u00e1is en la plena pobreza! Si apreci\u00e1is vuestros recursos, por pocos que sean, o si los busc\u00e1is, os hall\u00e1is en el campo natural de las cosas, que es a menudo frecuentemente obstaculizado por Satan\u00e1s. Ning\u00fan razonador o ponderador ha hecho milagros, ni siquiera entre los santos:\u00a0<i>obra divinamente quien se abandona a Dios.<\/i><\/p>\n<p>Cuando veas que las cosas se complican, di con los ojos del alma cerrados: \u201c<b><i>Jes\u00fas, oc\u00fapate T\u00fa\u201d.<\/i><\/b>\u00a0Y distr\u00e1ete, ap\u00e1rtate de ti porque tu mente es penetrante\u2026 y para ti es dif\u00edcil ver el mal y tener confianza en m\u00ed. Haz as\u00ed para con todas tus necesidades; obrad as\u00ed todos y ver\u00e9is grandes, continuos y silenciosos milagros. Os lo juro por mi amor. Y yo me ocupar\u00e9 de ello, os lo aseguro.<\/p>\n<p>Rogad siempre con esta disposici\u00f3n de abandono y tendr\u00e9is gran paz y grandes frutos, incluso cuando yo os concedo la gracia de la inmolaci\u00f3n de reparaci\u00f3n y de amor, que importa el sufrimiento. \u00bfTe parece imposible?. Cierra los ojos y di con toda el alma: \u201c<b><i>Jes\u00fas, oc\u00fapate T\u00fa\u201d<\/i><\/b>. No temas, me ocupar\u00e9 de ello y bendecir\u00e1s mi Nombre humill\u00e1ndote. Mil plegarias no valen lo que un solo acto de abandono vale: recordadlo bien. No hay novena m\u00e1s eficaz que esta:\u00a0<b><i>\u00a1Oh Jes\u00fas me abandono en Ti, OC\u00daPATE T\u00da!<\/i><\/b><\/p>\n<p><iframe loading=\"lazy\" title=\"\u201cJes\u00fas, Oc\u00fapate T\u00fa\u201d. La oraci\u00f3n de abandono de Don Dolindo\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/I7wuc4sHVYc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del Padre Dolindo Ruotolo<\/p>\n","protected":false},"author":15,"featured_media":109833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[74],"tags":[26463,2034,1442,26456,26460,448,3164,2623,26146,26458,676,26462,26455,26461,26457,7012,26459,2000],"class_list":["post-105994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","tag-abandono-en-dios","tag-beatificacion","tag-confianza-en-dios","tag-don-dolindo-ruotolo","tag-entrega-a-cristo","tag-espiritu-santo","tag-fe-es","tag-jesus","tag-madre-maria","tag-mistico-napolitano","tag-oracion","tag-oracion-cristiana","tag-oracion-de-abandono","tag-oracion-de-entrega","tag-padre-dolindo","tag-padre-pio","tag-portavoz-del-espiritu-santo","tag-rosario-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oraci\u00f3n del abandono &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/oracion-de-abandono\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oraci\u00f3n del abandono &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Del Padre Dolindo Ruotolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/oracion-de-abandono\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T12:13:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T11:56:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"Oraci\u00f3n del abandono\",\"datePublished\":\"2024-10-02T12:13:17+00:00\",\"dateModified\":\"2026-01-14T11:56:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/\"},\"wordCount\":1433,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/152037_dolindo_ruotolo1.jpg\",\"keywords\":[\"abandono en Dios\",\"Beatificaci\u00f3n\",\"Confianza en Dios\",\"Don Dolindo Ruotolo\",\"entrega a Cristo\",\"Esp\u00edritu Santo\",\"fe\",\"Jes\u00fas\",\"madre Mar\u00eda\",\"m\u00edstico napolitano\",\"Oraci\u00f3n\",\"oraci\u00f3n cristiana\",\"Oraci\u00f3n de abandono\",\"oraci\u00f3n de entrega\",\"Padre Dolindo\",\"Padre P\u00edo\",\"portavoz del Esp\u00edritu Santo\",\"Rosario\"],\"articleSection\":[\"Iglesia y Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/\",\"name\":\"Oraci\u00f3n del abandono &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/152037_dolindo_ruotolo1.jpg\",\"datePublished\":\"2024-10-02T12:13:17+00:00\",\"dateModified\":\"2026-01-14T11:56:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/152037_dolindo_ruotolo1.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/152037_dolindo_ruotolo1.jpg\",\"width\":640,\"height\":360,\"caption\":\"Don Dolindo Ruotolo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/oracion-de-abandono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oraci\u00f3n del abandono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oraci\u00f3n del abandono &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/","og_locale":"es_ES","og_type":"article","og_title":"Oraci\u00f3n del abandono &#8211; Exaudi","og_description":"Del Padre Dolindo Ruotolo","og_url":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2024-10-02T12:13:17+00:00","article_modified_time":"2026-01-14T11:56:37+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"Oraci\u00f3n del abandono","datePublished":"2024-10-02T12:13:17+00:00","dateModified":"2026-01-14T11:56:37+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/"},"wordCount":1433,"image":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","keywords":["abandono en Dios","Beatificaci\u00f3n","Confianza en Dios","Don Dolindo Ruotolo","entrega a Cristo","Esp\u00edritu Santo","fe","Jes\u00fas","madre Mar\u00eda","m\u00edstico napolitano","Oraci\u00f3n","oraci\u00f3n cristiana","Oraci\u00f3n de abandono","oraci\u00f3n de entrega","Padre Dolindo","Padre P\u00edo","portavoz del Esp\u00edritu Santo","Rosario"],"articleSection":["Iglesia y Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/","url":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/","name":"Oraci\u00f3n del abandono &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","datePublished":"2024-10-02T12:13:17+00:00","dateModified":"2026-01-14T11:56:37+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/oracion-de-abandono\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","width":640,"height":360,"caption":"Don Dolindo Ruotolo"},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/oracion-de-abandono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"Oraci\u00f3n del abandono"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/152037_dolindo_ruotolo1.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-rzA","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/105994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=105994"}],"version-history":[{"count":4,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/105994\/revisions"}],"predecessor-version":[{"id":153633,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/105994\/revisions\/153633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/109833"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=105994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=105994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=105994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}