{"id":104772,"date":"2024-07-08T08:15:18","date_gmt":"2024-07-08T06:15:18","guid":{"rendered":"https:\/\/exaudi.org\/?p=104772"},"modified":"2024-07-08T07:33:05","modified_gmt":"2024-07-08T05:33:05","slug":"la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima","status":"publish","type":"post","link":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/","title":{"rendered":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima"},"content":{"rendered":"<p>Queridos amigos:<\/p>\n<p>Esta nota sigue donde la dejamos ayer, minutos antes de comenzar la Santa Misa, en la tarde del 6 de julio de 2024. La lluvia segu\u00eda cayendo, signo de las muchas bendiciones que se han derramado en estos d\u00edas sobre los m\u00e1s de 1600 participantes de la Jornada Europea de la Juventud Mariana (JEMJ). Por eso, nuestros corazones cantaban con el Coro de la JEMJ: \u00abTus planes son perfectos. De alegr\u00eda y paz llenas mi coraz\u00f3n\u00bb.<\/p>\n<p>Seg\u00fan nuestra forma de ver las cosas, hubi\u00e9ramos preferido un fin de semana sin lluvia, con una temperatura agradable y una nubecita cubriendo el sol al mediod\u00eda. Pero no cae una gota de agua del cielo sin que lo permita nuestro Se\u00f1or. Y es muy bueno que haya sido as\u00ed porque a veces caemos en la tentaci\u00f3n, sobre todo cuando trabajamos con j\u00f3venes, de procurarles una \u00abpiedad de sentimientos\u00bb. Y cuando vuelven al mundo y los sentimientos pasan, el mundo se les come. Este fin de semana, el fr\u00edo y la lluvia han dejado poco margen a los sentimientos. Y eso ha sido una bendici\u00f3n, porque el verdadero encuentro con Cristo vivo no se asienta sobre sentimientos, sino en la fe. La aparente \u00abadversidad\u00bb climatol\u00f3gica ha sido una insistente invitaci\u00f3n del Se\u00f1or a no quedarnos en los sentimientos, sino a buscar una profunda relaci\u00f3n con \u00c9l y con su Madre Sant\u00edsima, en la oraci\u00f3n y en los sacramentos, especialmente en la Eucarist\u00eda y en la Penitencia, sin esconderles \u00abel esc\u00e1ndalo de la cruz\u00bb (Cfr. 1 Co 1,18).<\/p>\n<p>Los sacerdotes no han dejado de confesar todo el fin de semana. La Santa Misa de la tarde del s\u00e1bado, presidida por Mons. D. Jes\u00fas Sanz Montes y predicada por el abad de Covadonga, D. Adolfo Mari\u00f1o, tuvo que ser trasladada al interior de la bas\u00edlica, literalmente a rebosar de j\u00f3venes. Los que no cab\u00edan dentro, tuvieron que seguir la Santa Misa desde las carpas. Y sin embargo, la belleza de la liturgia y de los cantos habl\u00f3 al coraz\u00f3n de los j\u00f3venes.<\/p>\n<p>En este <a href=\"https:\/\/www.youtube.com\/watch?v=czRzCLU4sMI\" target=\"_blank\" rel=\"noopener\">enlace<\/a> tienen la Santa Misa del 6 de julio de 2024. A partir del minuto 23, encuentran la intervenci\u00f3n de Mons. Sanz Montes antes de la homil\u00eda y la homil\u00eda de D. Adolfo Mari\u00f1o.<\/p>\n<p>Y lleg\u00f3 al fin la Gran Vigilia de Adoraci\u00f3n Eucar\u00edstica. La lluvia hab\u00eda cesado y pudo mantenerse en el exterior de la Bas\u00edlica, como estaba programada. Aunque la explanada estaba empapada de agua y el fr\u00edo de la monta\u00f1a asturiana iba calando poco a poco, el silencio y el ambiente de adoraci\u00f3n prevalecieron sobre el fr\u00edo y el agua. La polic\u00eda avis\u00f3 al abad de que se iba: con esos j\u00f3venes all\u00ed reunidos, ellos no eran necesarios en Covadonga.<\/p>\n<p>La Vigilia fue presidida por una r\u00e9plica de la \u00abCruz de la Victoria\u00bb que hay que explicar. Cuentan las cr\u00f3nicas que Don Pelayo llev\u00f3 a la batalla de Covadonga una cruz de madera que se convirti\u00f3 en el estandarte de su ej\u00e9rcito y en s\u00edmbolo del esp\u00edritu con el cual luchaba. Los descendientes de Pelayo conservaron esa cruz y la hicieron recubrir de oro y piedras preciosas, conserv\u00e1ndose en la Catedral de Oviedo. La JEMJ ha querido volver a tomar la cruz como estandarte que nos gu\u00eda hasta el triunfo del Coraz\u00f3n Inmaculado de Mar\u00eda. Cada JEMJ se convertir\u00e1 as\u00ed en una nueva batalla donde los j\u00f3venes se reunir\u00e1n en torno a la \u00abCruz de la Victoria\u00bb.<\/p>\n<p>La nueva cruz es de madera, tallada y dorada. Mide 140 cent\u00edmetros de alta por 106 de ancha. Fue colocada en el altar sobre una base de piedra tallada en la que se represent\u00f3 el martirio de San Pedro junto con la inscripci\u00f3n \u00abTu es Petrus\u00bb: una profesi\u00f3n de fe en nuestra Santa Madre la Iglesia y en el primado del Pedro.<\/p>\n<p>Terminada la Vigilia, el Sant\u00edsimo fue conducido en una solemne procesi\u00f3n hasta la Santa Cueva de la Virgen de Covadonga. Los j\u00f3venes acompa\u00f1aron a Jes\u00fas Sacramentado en turnos de adoraci\u00f3n a lo largo de toda la noche. Los detalles de la Gran Vigilia de Adoraci\u00f3n Eucar\u00edstica pueden seguirlos en este <a href=\"https:\/\/www.youtube.com\/watch?v=anKlII-fcLQ\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n<p>La ma\u00f1ana del 7 de julio de 2024, comenz\u00f3 con un tiempo de adoraci\u00f3n eucar\u00edstica. La lluvia hab\u00eda cesado y todos los actos previstos pudieron tenerse en la explanada. Los puntos de meditaci\u00f3n estuvieron a cargo del P. Rafael Alonso Reymundo. Pueden escucharlos de nuevo en este <a href=\"https:\/\/www.youtube.com\/watch?v=hv_Luq-TxbU\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n<p>A las 12 de la ma\u00f1ana, comenz\u00f3 la Santa Misa de clausura de la JEMJ, presidido por Mons. D. Jes\u00fas Sanz Montes, arzobispo de Oviedo, concelebrada por unos veinte sacerdotes. El resto de los sacerdotes presentes en la JEMJ estuvieron disponibles para la confesi\u00f3n. La homil\u00eda de Mons. Sanz ha terminado diciendo: \u00ab(La JEMJ) ha sido una gracia de Dios inmensa, que la Archidi\u00f3cesis de Oviedo ha tenido la bendici\u00f3n de acoger y acompa\u00f1ar\u00bb.<\/p>\n<p>Pueden escuchar la homil\u00eda completa a partir del minuto 26 de la grabaci\u00f3n de la Santa Misa o leerla en el archivo adjunto: <a href=\"https:\/\/www.youtube.com\/watch?v=GBUpHQek9P0\" target=\"_blank\" rel=\"noopener\">ver homil\u00eda<\/a>.<\/p>\n<p>Al terminar la Santa Misa, el arzobispo de Oviedo ha invitado al P. Rafael Alonso, fundador del Hogar de la Madre, ha hacer p\u00fablica la fecha y el lugar de la pr\u00f3xima JEMJ: ser\u00e1 de nuevo en el Santuario de Covadonga, del 4 al 6 de julio de 2025.<\/p>\n<p>D. Jes\u00fas ha querido dejar sus impresiones sobre lo vivido en este breve <a href=\"https:\/\/www.youtube.com\/watch?v=X2slNNcI2Og\" target=\"_blank\" rel=\"noopener\">v\u00eddeo<\/a>.<\/p>\n<p>En el canal de YouTube \u00ab<a href=\"https:\/\/www.youtube.com\/@ENMARCHAJEMJ\/videos\" target=\"_blank\" rel=\"noopener\">En marcha JEMJ<\/a>\u00bb encontrar\u00e1n breves v\u00eddeos que pongan im\u00e1genes a todo lo que explicamos. Unos ya est\u00e1n subidos, otros se ir\u00e1n subiendo a lo largo de la semana.<\/p>\n<p>Y completaremos la actualizaci\u00f3n de fotos, v\u00eddeos y textos en este <a href=\"https:\/\/drive.google.com\/drive\/folders\/1UXxrgVQ3C0eshQKKGpwr8vPm84M6EozQ\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n<p>Y dentro de poco, se abrir\u00e1n de nuevo las inscripciones para la siguiente JEMJ, para la pr\u00f3xima batalla de esta nueva Reconquista de los j\u00f3venes para Jesucristo. Contamos con su difusi\u00f3n y con sus oraciones.<\/p>\n<p>Que Nuestra Madre del Cielo les bendiga.<\/p>\n<p>Hna. Beatriz Lia\u00f1o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00f3nica de Hna. Beatriz Lia\u00f1o<\/p>\n","protected":false},"author":15,"featured_media":104773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[74,98],"tags":[19013,6004,1685,20789,1595,2002,3164,20790,14496,1855,676,9719,4953],"class_list":["post-104772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iglesia-y-mundo","category-testimonios","tag-adoracion","tag-clima-es","tag-confesion","tag-covadonga","tag-encuentro","tag-eucaristia-es","tag-fe-es","tag-hna-beatriz-liano","tag-jemj","tag-jovenes","tag-oracion","tag-sacramentos","tag-trending-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi\" \/>\n<meta property=\"og:description\" content=\"Cr\u00f3nica de Hna. Beatriz Lia\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/\" \/>\n<meta property=\"og:site_name\" content=\"Exaudi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ExaudiNews\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ExaudiNoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T06:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exaudi Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Exaudi_noticias\" \/>\n<meta name=\"twitter:site\" content=\"@Exaudi_News\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exaudi Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/\"},\"author\":{\"name\":\"Exaudi Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"headline\":\"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima\",\"datePublished\":\"2024-07-08T06:15:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/\"},\"wordCount\":1076,\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/0E9A3803-scaled.jpg\",\"keywords\":[\"Adoraci\u00f3n\",\"Clima\",\"Confesi\u00f3n\",\"Covadonga\",\"Encuentro\",\"Eucaristia\",\"fe\",\"Hna. Beatriz Lia\u00f1o\",\"JEMJ\",\"J\u00f3venes\",\"Oraci\u00f3n\",\"SACRAMENTOS\",\"Trending\"],\"articleSection\":[\"Iglesia y Mundo\",\"Testimonios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/\",\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/\",\"name\":\"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/0E9A3803-scaled.jpg\",\"datePublished\":\"2024-07-08T06:15:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/0E9A3803-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exaudi.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/0E9A3803-scaled.jpg\",\"width\":2560,\"height\":1437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/es\\\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exaudi.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#website\",\"url\":\"https:\\\/\\\/exaudi.org\\\/\",\"name\":\"Exaudi\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exaudi.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exaudi.org\\\/#\\\/schema\\\/person\\\/f5fc8f063065e38742da7afe15f25df7\",\"name\":\"Exaudi Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g\",\"caption\":\"Exaudi Redacci\u00f3n\"},\"description\":\"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\\\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ExaudiNoticias\\\/\",\"https:\\\/\\\/www.instagram.com\\\/exaudi_noticias\\\/\",\"https:\\\/\\\/x.com\\\/Exaudi_noticias\",\"https:\\\/\\\/www.youtube.com\\\/@exaudicatholicnews\"],\"url\":\"https:\\\/\\\/exaudi.org\\\/es\\\/author\\\/redaccionexaudi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/","og_locale":"es_ES","og_type":"article","og_title":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi","og_description":"Cr\u00f3nica de Hna. Beatriz Lia\u00f1o","og_url":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/","og_site_name":"Exaudi","article_publisher":"https:\/\/www.facebook.com\/ExaudiNews","article_author":"https:\/\/www.facebook.com\/ExaudiNoticias\/","article_published_time":"2024-07-08T06:15:18+00:00","og_image":[{"width":2560,"height":1437,"url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","type":"image\/jpeg"}],"author":"Exaudi Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Exaudi_noticias","twitter_site":"@Exaudi_News","twitter_misc":{"Escrito por":"Exaudi Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#article","isPartOf":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/"},"author":{"name":"Exaudi Redacci\u00f3n","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"headline":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima","datePublished":"2024-07-08T06:15:18+00:00","mainEntityOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/"},"wordCount":1076,"image":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","keywords":["Adoraci\u00f3n","Clima","Confesi\u00f3n","Covadonga","Encuentro","Eucaristia","fe","Hna. Beatriz Lia\u00f1o","JEMJ","J\u00f3venes","Oraci\u00f3n","SACRAMENTOS","Trending"],"articleSection":["Iglesia y Mundo","Testimonios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/","url":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/","name":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima &#8211; Exaudi","isPartOf":{"@id":"https:\/\/exaudi.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#primaryimage"},"image":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#primaryimage"},"thumbnailUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","datePublished":"2024-07-08T06:15:18+00:00","author":{"@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7"},"breadcrumb":{"@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#primaryimage","url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","contentUrl":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","width":2560,"height":1437},{"@type":"BreadcrumbList","@id":"https:\/\/exaudi.org\/es\/la-jemj-en-covadonga-un-encuentro-profundo-con-la-fe-a-pesar-del-clima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exaudi.org\/es\/"},{"@type":"ListItem","position":2,"name":"La JEMJ en Covadonga: Un Encuentro Profundo con la Fe a Pesar del Clima"}]},{"@type":"WebSite","@id":"https:\/\/exaudi.org\/#website","url":"https:\/\/exaudi.org\/","name":"Exaudi","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exaudi.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/exaudi.org\/#\/schema\/person\/f5fc8f063065e38742da7afe15f25df7","name":"Exaudi Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe0f6a059fb68d9b3e11bc5850dd4899b1c7492091a3cb6dd9b01b56ad828be2?s=96&d=mm&r=g","caption":"Exaudi Redacci\u00f3n"},"description":"\u00bfQu\u00e9 es Exaudi News? Exaudi News es un medio de comunicaci\u00f3n cat\u00f3lico internacional que informa, forma y transforma, diariamente en espa\u00f1ol, ingl\u00e9s e italiano. A trav\u00e9s de noticias, art\u00edculos de an\u00e1lisis y transmisiones en directo de los eventos del Papa, Exaudi busca fortalecer la unidad de los cristianos y contribuir a la evangelizaci\u00f3n del mundo, siempre guiados por la doctrina social de la Iglesia. Trabajamos para acercar la verdad y los valores cristianos a cada rinc\u00f3n del planeta. \u00a1Ay\u00fadanos a transformar el mundo con Exaudi! En Exaudi creemos que la evangelizaci\u00f3n y la informaci\u00f3n de calidad pueden cambiar vidas. Para continuar con nuestra misi\u00f3n y expandir nuestro alcance, necesitamos tu ayuda. Adem\u00e1s, buscamos personas comprometidas que deseen unirse a nuestro equipo. Con tu apoyo, lograremos llegar a m\u00e1s personas, difundir el mensaje de Cristo y reforzar la unidad de los cristianos. \u00bfTe unes a nuestra misi\u00f3n? Para m\u00e1s informaci\u00f3n sobre c\u00f3mo colaborar, visita Exaudi.org\/es o cont\u00e1ctanos directamente: info@exaudi.org Exaudi: Informa, forma y transforma.","sameAs":["https:\/\/www.facebook.com\/ExaudiNoticias\/","https:\/\/www.instagram.com\/exaudi_noticias\/","https:\/\/x.com\/Exaudi_noticias","https:\/\/www.youtube.com\/@exaudicatholicnews"],"url":"https:\/\/exaudi.org\/es\/author\/redaccionexaudi\/"}]}},"jetpack_featured_media_url":"https:\/\/exaudi.org\/wp-content\/uploads\/2024\/07\/0E9A3803-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgKjF2-rfS","_links":{"self":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/104772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/comments?post=104772"}],"version-history":[{"count":0,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/posts\/104772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media\/104773"}],"wp:attachment":[{"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/media?parent=104772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/categories?post=104772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exaudi.org\/es\/wp-json\/wp\/v2\/tags?post=104772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}